{"id":169343,"date":"2022-12-13T12:24:02","date_gmt":"2022-12-13T12:24:02","guid":{"rendered":"https:\/\/www.horendgoed.nl\/shop\/sin%20categor\u00eda\/phonak-cupula-4-0-media-abierta-10-piezas\/"},"modified":"2025-07-22T15:45:58","modified_gmt":"2025-07-22T13:45:58","slug":"phonak-cupula-4-0-media-abierta-10-piezas","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/","title":{"rendered":"Phonak C\u00fapula 4.0 Media Abierta 10 piezas"},"content":{"rendered":"<p>Phonak SDS 4.0 - C\u00fapulas - Para Marvel y Paradise - Medianamente abiertas - Bl\u00edster de 10 unidades<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Phonak SDS 4.0 - C\u00fapulas - Para Marvel y Paradise - Medianamente abiertas - Bl\u00edster de 10 unidades<\/p>\n","protected":false},"featured_media":169361,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[12361,12529],"product_tag":[13932],"class_list":["post-169343","product","type-product","status-publish","has-post-thumbnail","product_cat-accesorios","product_cat-cupulas","product_tag-phonak-es","grid-sizer","latest_post","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Phonak C\u00fapula 4.0 Media Abierta 10 piezas | Horend Goed Audiciens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Phonak C\u00fapula 4.0 Media Abierta 10 piezas\" \/>\n<meta property=\"og:description\" content=\"Phonak SDS 4.0 - C\u00fapulas - Para Marvel y Paradise - Medianamente abiertas - Bl\u00edster de 10 unidades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T13:45:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/c9dc-4542-42ae-962b-3ef43e7047af-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"545\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/shop\\\/accesorios\\\/cupulas\\\/phonak-cupula-4-0-media-abierta-10-piezas\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/shop\\\/accesorios\\\/cupulas\\\/phonak-cupula-4-0-media-abierta-10-piezas\\\/\",\"name\":\"Phonak C\u00fapula 4.0 Media Abierta 10 piezas | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/shop\\\/accesorios\\\/cupulas\\\/phonak-cupula-4-0-media-abierta-10-piezas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/shop\\\/accesorios\\\/cupulas\\\/phonak-cupula-4-0-media-abierta-10-piezas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/c9dc-4542-42ae-962b-3ef43e7047af-1.jpg\",\"datePublished\":\"2022-12-13T12:24:02+00:00\",\"dateModified\":\"2025-07-22T13:45:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/shop\\\/accesorios\\\/cupulas\\\/phonak-cupula-4-0-media-abierta-10-piezas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/shop\\\/accesorios\\\/cupulas\\\/phonak-cupula-4-0-media-abierta-10-piezas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/shop\\\/accesorios\\\/cupulas\\\/phonak-cupula-4-0-media-abierta-10-piezas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/c9dc-4542-42ae-962b-3ef43e7047af-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/c9dc-4542-42ae-962b-3ef43e7047af-1.jpg\",\"width\":550,\"height\":545},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/shop\\\/accesorios\\\/cupulas\\\/phonak-cupula-4-0-media-abierta-10-piezas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/tienda\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Phonak C\u00fapula 4.0 Media Abierta 10 piezas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Phonak C\u00fapula 4.0 Media Abierta 10 piezas | Horend Goed Audiciens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/","og_locale":"es_ES","og_type":"article","og_title":"Phonak C\u00fapula 4.0 Media Abierta 10 piezas","og_description":"Phonak SDS 4.0 - C\u00fapulas - Para Marvel y Paradise - Medianamente abiertas - Bl\u00edster de 10 unidades","og_url":"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","article_modified_time":"2025-07-22T13:45:58+00:00","og_image":[{"width":550,"height":545,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/c9dc-4542-42ae-962b-3ef43e7047af-1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/","url":"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/","name":"Phonak C\u00fapula 4.0 Media Abierta 10 piezas | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/c9dc-4542-42ae-962b-3ef43e7047af-1.jpg","datePublished":"2022-12-13T12:24:02+00:00","dateModified":"2025-07-22T13:45:58+00:00","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/c9dc-4542-42ae-962b-3ef43e7047af-1.jpg","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/c9dc-4542-42ae-962b-3ef43e7047af-1.jpg","width":550,"height":545},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/es\/shop\/accesorios\/cupulas\/phonak-cupula-4-0-media-abierta-10-piezas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.horendgoed.nl\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/www.horendgoed.nl\/es\/tienda\/productos\/"},{"@type":"ListItem","position":3,"name":"Phonak C\u00fapula 4.0 Media Abierta 10 piezas"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/es\/#website","url":"https:\/\/www.horendgoed.nl\/es\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/es\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.horendgoed.nl\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/es\/wp-json\/wp\/v2\/product\/169343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/es\/wp-json\/wp\/v2\/media\/169361"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/es\/wp-json\/wp\/v2\/media?parent=169343"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/es\/wp-json\/wp\/v2\/product_brand?post=169343"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/es\/wp-json\/wp\/v2\/product_cat?post=169343"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/es\/wp-json\/wp\/v2\/product_tag?post=169343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}