{"id":187679,"date":"2022-12-13T13:13:21","date_gmt":"2022-12-13T12:13:21","guid":{"rendered":"https:\/\/www.horendgoed.nl\/shop\/non%20class\u00e9\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/"},"modified":"2025-04-28T08:58:04","modified_gmt":"2025-04-28T06:58:04","slug":"cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/","title":{"rendered":"Cedis Brosses spirales \u00af 2.5 mm - 10 pi\u00e8ces"},"content":{"rendered":"<p>Ces brosses Cedis sont particuli\u00e8rement adapt\u00e9es au nettoyage des tubes sonores tr\u00e8s fins et des \u00e9vents (2,5 mm). Pour une hygi\u00e8ne optimale de votre appareil auditif. Une bo\u00eete contient 10 brosses spirales.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ces brosses Cedis sont particuli\u00e8rement adapt\u00e9es au nettoyage des tubes sonores tr\u00e8s fins et des \u00e9vents (2,5 mm). Pour une hygi\u00e8ne optimale de votre appareil auditif. Une bo\u00eete contient 10 brosses spirales.<\/p>\n","protected":false},"featured_media":187681,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[14131],"product_tag":[],"class_list":["post-187679","product","type-product","status-publish","has-post-thumbnail","product_cat-nettoyeurs-de-protheses-auditives","grid-sizer","latest_post","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cedis Brosses spirales \u00af 2.5 mm - 10 pi\u00e8ces | Horend Goed Audiciens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cedis Brosses spirales \u00af 2.5 mm - 10 pi\u00e8ces\" \/>\n<meta property=\"og:description\" content=\"Ces brosses Cedis sont particuli\u00e8rement adapt\u00e9es au nettoyage des tubes sonores tr\u00e8s fins et des \u00e9vents (2,5 mm). Pour une hygi\u00e8ne optimale de votre appareil auditif. Une bo\u00eete contient 10 brosses spirales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T06:58:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/97ba-52a4-4b15-aed8-4a3d13c6c76d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"811\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/nettoyeurs-de-protheses-auditives\\\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/nettoyeurs-de-protheses-auditives\\\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\\\/\",\"name\":\"Cedis Brosses spirales \u00af 2.5 mm - 10 pi\u00e8ces | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/nettoyeurs-de-protheses-auditives\\\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/nettoyeurs-de-protheses-auditives\\\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/97ba-52a4-4b15-aed8-4a3d13c6c76d.jpg\",\"datePublished\":\"2022-12-13T12:13:21+00:00\",\"dateModified\":\"2025-04-28T06:58:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/nettoyeurs-de-protheses-auditives\\\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/nettoyeurs-de-protheses-auditives\\\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/nettoyeurs-de-protheses-auditives\\\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/97ba-52a4-4b15-aed8-4a3d13c6c76d.jpg\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/97ba-52a4-4b15-aed8-4a3d13c6c76d.jpg\",\"width\":550,\"height\":811},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/nettoyeurs-de-protheses-auditives\\\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/boutique\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cedis Brosses spirales \u00af 2.5 mm - 10 pi\u00e8ces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cedis Brosses spirales \u00af 2.5 mm - 10 pi\u00e8ces | Horend Goed Audiciens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/","og_locale":"fr_FR","og_type":"article","og_title":"Cedis Brosses spirales \u00af 2.5 mm - 10 pi\u00e8ces","og_description":"Ces brosses Cedis sont particuli\u00e8rement adapt\u00e9es au nettoyage des tubes sonores tr\u00e8s fins et des \u00e9vents (2,5 mm). Pour une hygi\u00e8ne optimale de votre appareil auditif. Une bo\u00eete contient 10 brosses spirales.","og_url":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","article_modified_time":"2025-04-28T06:58:04+00:00","og_image":[{"width":550,"height":811,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/97ba-52a4-4b15-aed8-4a3d13c6c76d.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/","url":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/","name":"Cedis Brosses spirales \u00af 2.5 mm - 10 pi\u00e8ces | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/97ba-52a4-4b15-aed8-4a3d13c6c76d.jpg","datePublished":"2022-12-13T12:13:21+00:00","dateModified":"2025-04-28T06:58:04+00:00","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/97ba-52a4-4b15-aed8-4a3d13c6c76d.jpg","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/97ba-52a4-4b15-aed8-4a3d13c6c76d.jpg","width":550,"height":811},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/nettoyeurs-de-protheses-auditives\/cedis-brosses-spirales-%c2%af-2-5-mm-10-pieces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.horendgoed.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.horendgoed.nl\/fr\/boutique\/produits\/"},{"@type":"ListItem","position":3,"name":"Cedis Brosses spirales \u00af 2.5 mm - 10 pi\u00e8ces"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/fr\/#website","url":"https:\/\/www.horendgoed.nl\/fr\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/fr\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.horendgoed.nl\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/product\/187679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/media\/187681"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/media?parent=187679"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/product_brand?post=187679"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/product_cat?post=187679"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/product_tag?post=187679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}