{"id":262527,"date":"2025-10-14T11:18:14","date_gmt":"2025-10-14T09:18:14","guid":{"rendered":"https:\/\/www.horendgoed.nl\/?post_type=product&#038;p=262527"},"modified":"2025-10-14T11:36:45","modified_gmt":"2025-10-14T09:36:45","slug":"filtres-oticon-prowax-minifit-kopie","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/","title":{"rendered":"Filtres Oticon ProWax Minifit - nouvel emballage"},"content":{"rendered":"<p><strong>Oticon ProWax MiniFit System : Filtres originaux pour une utilisation optimale des aides auditives<\/strong><\/p>\n<p>Les <strong>filtres ProWax MiniFit d&rsquo;Oticon<\/strong> sont sp\u00e9cialement con\u00e7us pour maintenir vos aides auditives en parfait \u00e9tat. Ces filtres offrent une protection fiable contre le c\u00e9rumen, l&rsquo;humidit\u00e9 et la salet\u00e9, afin que vos aides auditives fonctionnent au mieux. Adapt\u00e9 aux marques d&rsquo;appareils auditifs <strong>Oticon<\/strong>, <strong>Bernafon<\/strong> et <strong>Philips<\/strong>, ce syst\u00e8me de filtre est un \u00e9l\u00e9ment essentiel de l&rsquo;entretien de vos appareils auditifs. Un paquet contient six filtres de rechange, faciles \u00e0 remplacer en cas de besoin.   <\/p>\n<h3>Pourquoi les filtres Oticon ProWax MiniFit sont-ils essentiels ?<\/h3>\n<p>Remplacer r\u00e9guli\u00e8rement les filtres de votre aide auditive est essentiel pour une qualit\u00e9 sonore claire et une longue dur\u00e9e de vie de l&rsquo;appareil. L&rsquo;utilisation de filtres Oticon ProWax MiniFit d&rsquo;origine permet d&rsquo;\u00e9viter que le c\u00e9rumen, l&rsquo;humidit\u00e9 ou d&rsquo;autres d\u00e9bris ne p\u00e9n\u00e8trent dans le haut-parleur de votre aide auditive. Sans cette protection, votre aide auditive risque de mal fonctionner, voire de tomber en panne.  <\/p>\n<h3>Avantages des filtres Oticon ProWax MiniFit<\/h3>\n<ul>\n<li><strong>Protection contre le c\u00e9rumen et la salet\u00e9 : Les<\/strong> filtres ProWax MiniFit d&rsquo;Oticon prot\u00e8gent l&rsquo;int\u00e9rieur de votre aide auditive contre l&rsquo;accumulation de c\u00e9rumen et d&rsquo;autres d\u00e9bris. Cela garantit que le haut-parleur reste libre de toute obstruction et que votre aide auditive continue \u00e0 fonctionner sans probl\u00e8me. <\/li>\n<li><strong>Facile \u00e0 remplacer :<\/strong> Ces filtres sont faciles \u00e0 remplacer, sans devoir faire appel \u00e0 un sp\u00e9cialiste. Vous pouvez le faire vous-m\u00eame \u00e0 la maison en suivant les instructions fournies. <\/li>\n<li><strong>Convient \u00e0 plusieurs marques :<\/strong> Outre les aides auditives Oticon, les filtres ProWax MiniFit sont \u00e9galement compatibles avec les aides auditives Bernafon et Philips. Ces filtres constituent donc un choix polyvalent pour les utilisateurs de diff\u00e9rentes marques d&rsquo;appareils auditifs. <\/li>\n<\/ul>\n<h3>L&rsquo;importance d&rsquo;un entretien r\u00e9gulier<\/h3>\n<p>Pour un confort auditif optimal, il est important de changer r\u00e9guli\u00e8rement le filtre de votre appareil auditif. La fr\u00e9quence de cette op\u00e9ration d\u00e9pend de la quantit\u00e9 de c\u00e9rumen que vous produisez et de l&rsquo;environnement dans lequel vous utilisez votre appareil auditif. Oticon recommande de v\u00e9rifier le filtre chaque semaine et de le remplacer si n\u00e9cessaire. Cela peut varier d&rsquo;un utilisateur \u00e0 l&rsquo;autre, mais un remplacement en temps voulu emp\u00eachera la d\u00e9t\u00e9rioration des performances de votre appareil auditif.   <\/p>\n<h3>Comment reconna\u00eetre un filtre bouch\u00e9 ?<\/h3>\n<p>Il est facile de savoir quand un filtre doit \u00eatre remplac\u00e9. Si le son devient moins clair, fluctue ou dispara\u00eet, cela peut indiquer que le filtre est obstru\u00e9 par du c\u00e9rumen ou des salet\u00e9s. Un filtre compl\u00e8tement bouch\u00e9 peut m\u00eame donner l&rsquo;impression que l&rsquo;aide auditive est d\u00e9fectueuse. En v\u00e9rifiant et en rempla\u00e7ant r\u00e9guli\u00e8rement le filtre, vous \u00e9viterez de vous retrouver sans appareil auditif fonctionnant correctement \u00e0 des moments cruciaux.   <\/p>\n<h3>Diff\u00e9rents filtres pour diff\u00e9rentes aides auditives<\/h3>\n<p>Oticon propose diff\u00e9rents types de filtres sp\u00e9cifiquement adapt\u00e9s \u00e0 certaines aides auditives. Il est important de toujours utiliser le bon type de filtre pour votre appareil auditif afin de garantir les meilleures performances. Les filtres ProWax MiniFit conviennent aux aides auditives \u00e9quip\u00e9es de haut-parleurs, telles que les appareils intra-auriculaires et les aides auditives sur mesure.  <\/p>\n<h3>Instructions pour le remplacement<\/h3>\n<p>Le remplacement des filtres ProWax MiniFit est facile. Suivez les \u00e9tapes suivantes pour remplacer correctement le filtre : <\/p>\n<ol>\n<li>Retirez l&rsquo;ancien filtre \u00e0 l&rsquo;aide de l&rsquo;outil appropri\u00e9.<\/li>\n<li>Ins\u00e9rez soigneusement le nouveau filtre dans l&rsquo;ouverture de l&rsquo;enceinte.<\/li>\n<li>V\u00e9rifiez que le filtre est correctement fix\u00e9 et qu&rsquo;aucune salet\u00e9 n&rsquo;est rest\u00e9e dans l&rsquo;ouverture de l&rsquo;enceinte.<\/li>\n<\/ol>\n<p>Il s&rsquo;agit d&rsquo;un processus simple que vous pouvez effectuer \u00e0 la maison et qui ne prend que quelques minutes.<\/p>\n<h3>La solution parfaite pour votre aide auditive<\/h3>\n<p>Les filtres ProWax MiniFit d&rsquo;Oticon permettent \u00e0 vos aides auditives de fonctionner au mieux. Un entretien r\u00e9gulier et le remplacement des filtres garantissent une qualit\u00e9 sonore claire et constante et pr\u00e9viennent les probl\u00e8mes tels que la distorsion du son ou la d\u00e9faillance compl\u00e8te de l&rsquo;appareil. <\/p>\n<p>Gr\u00e2ce \u00e0 leur conception intelligente, les filtres ProWax MiniFit offrent non seulement une excellente protection, mais ils prolongent \u00e9galement la dur\u00e9e de vie de votre aide auditive. Cela signifie des r\u00e9parations ou des remplacements moins fr\u00e9quents, ce qui vous permet d&rsquo;\u00e9conomiser du temps et de l&rsquo;argent. <\/p>\n<h3>Commandez d\u00e8s aujourd&rsquo;hui vos filtres Oticon ProWax MiniFit<\/h3>\n<p>N&rsquo;attendez pas que votre aide auditive se d\u00e9t\u00e9riore - assurez-vous d&rsquo;avoir toujours un stock de <strong>filtres Oticon ProWax MiniFit<\/strong> \u00e0 port\u00e9e de main. Avec un pack de six filtres, vous serez bien pr\u00e9par\u00e9 pour le prochain remplacement et pourrez continuer \u00e0 profiter d&rsquo;une exp\u00e9rience sonore optimale en toute confiance. <\/p>\n<h3>Convient aux appareils auditifs Oticon, Bernafon et Philips<\/h3>\n<p>Que vous utilisiez une aide auditive Oticon, Bernafon ou Philips, les filtres Oticon ProWax MiniFit offrent une protection fiable et d&rsquo;excellentes performances. Choisissez des filtres d&rsquo;origine pour garantir la meilleure qualit\u00e9 et la meilleure compatibilit\u00e9 avec votre appareil auditif. <\/p>\n<p><strong>Veuillez noter que les<\/strong> appareils auditifs intra-auriculaires et les coques personnalis\u00e9es utilisent des filtres ProWax.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oticon ProWax MiniFit System : Filtres originaux pour une utilisation optimale des aides auditives Les filtres ProWax MiniFit d&rsquo;Oticon sont sp\u00e9cialement con\u00e7us pour maintenir vos aides auditives en parfait \u00e9tat. Ces filtres offrent une protection fiable contre le c\u00e9rumen, l&rsquo;humidit\u00e9 et la salet\u00e9, afin que vos aides auditives fonctionnent au mieux. Adapt\u00e9 aux marques d&rsquo;appareils &hellip; <\/p>\n","protected":false},"featured_media":262512,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[14107,14263],"product_tag":[14256,14257],"class_list":["post-262527","product","type-product","status-publish","has-post-thumbnail","product_cat-accessoires-fr","product_cat-filtres","product_tag-bernafon-fr","product_tag-oticon-fr","grid-sizer","latest_post","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Filtres Prowax minifit d&#039;Oticon | Horend Goed Audiciens<\/title>\n<meta name=\"description\" content=\"Filtres Oticon Prowax minifit pour les appareils auditifs \u00e0 haut-parleur d&#039;Oticon, Bernafon, Philips. Commandez-les facilement chez Horend Goed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filtres Oticon ProWax Minifit - nouvel emballage\" \/>\n<meta property=\"og:description\" content=\"Filtres Oticon Prowax minifit pour les appareils auditifs \u00e0 haut-parleur d&#039;Oticon, Bernafon, Philips. Commandez-les facilement chez Horend Goed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T09:36:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/Horend-Goed-Oticon-minifit-Prowax-nieuwe-verpakking.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/filtres\\\/filtres-oticon-prowax-minifit-kopie\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/filtres\\\/filtres-oticon-prowax-minifit-kopie\\\/\",\"name\":\"Filtres Prowax minifit d'Oticon | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/filtres\\\/filtres-oticon-prowax-minifit-kopie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/filtres\\\/filtres-oticon-prowax-minifit-kopie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Horend-Goed-Oticon-minifit-Prowax-nieuwe-verpakking.jpg\",\"datePublished\":\"2025-10-14T09:18:14+00:00\",\"dateModified\":\"2025-10-14T09:36:45+00:00\",\"description\":\"Filtres Oticon Prowax minifit pour les appareils auditifs \u00e0 haut-parleur d'Oticon, Bernafon, Philips. Commandez-les facilement chez Horend Goed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/filtres\\\/filtres-oticon-prowax-minifit-kopie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/filtres\\\/filtres-oticon-prowax-minifit-kopie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/filtres\\\/filtres-oticon-prowax-minifit-kopie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Horend-Goed-Oticon-minifit-Prowax-nieuwe-verpakking.jpg\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Horend-Goed-Oticon-minifit-Prowax-nieuwe-verpakking.jpg\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/shop\\\/accessoires-fr\\\/filtres\\\/filtres-oticon-prowax-minifit-kopie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/boutique\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Filtres Oticon ProWax Minifit - nouvel emballage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Filtres Prowax minifit d'Oticon | Horend Goed Audiciens","description":"Filtres Oticon Prowax minifit pour les appareils auditifs \u00e0 haut-parleur d'Oticon, Bernafon, Philips. Commandez-les facilement chez Horend Goed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/","og_locale":"fr_FR","og_type":"article","og_title":"Filtres Oticon ProWax Minifit - nouvel emballage","og_description":"Filtres Oticon Prowax minifit pour les appareils auditifs \u00e0 haut-parleur d'Oticon, Bernafon, Philips. Commandez-les facilement chez Horend Goed.","og_url":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","article_modified_time":"2025-10-14T09:36:45+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/Horend-Goed-Oticon-minifit-Prowax-nieuwe-verpakking.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/","url":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/","name":"Filtres Prowax minifit d'Oticon | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/Horend-Goed-Oticon-minifit-Prowax-nieuwe-verpakking.jpg","datePublished":"2025-10-14T09:18:14+00:00","dateModified":"2025-10-14T09:36:45+00:00","description":"Filtres Oticon Prowax minifit pour les appareils auditifs \u00e0 haut-parleur d'Oticon, Bernafon, Philips. Commandez-les facilement chez Horend Goed.","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/Horend-Goed-Oticon-minifit-Prowax-nieuwe-verpakking.jpg","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/Horend-Goed-Oticon-minifit-Prowax-nieuwe-verpakking.jpg","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/fr\/shop\/accessoires-fr\/filtres\/filtres-oticon-prowax-minifit-kopie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.horendgoed.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.horendgoed.nl\/fr\/boutique\/produits\/"},{"@type":"ListItem","position":3,"name":"Filtres Oticon ProWax Minifit - nouvel emballage"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/fr\/#website","url":"https:\/\/www.horendgoed.nl\/fr\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/fr\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.horendgoed.nl\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/product\/262527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/media\/262512"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/media?parent=262527"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/product_brand?post=262527"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/product_cat?post=262527"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/fr\/wp-json\/wp\/v2\/product_tag?post=262527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}