{"id":144175,"date":"2023-09-21T13:28:35","date_gmt":"2023-09-21T13:28:35","guid":{"rendered":"https:\/\/www.horendgoed.nl\/shop\/senza-categoria\/telecomando-intelligente-connexx\/"},"modified":"2025-09-15T11:09:04","modified_gmt":"2025-09-15T09:09:04","slug":"telecomando-intelligente-connexx","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/","title":{"rendered":"Servizio audioConnexx Smart Remote"},"content":{"rendered":"<h2 data-start=\"207\" data-end=\"279\">Connexx Smart Remote - Controlla i tuoi apparecchi acustici con facilit\u00e0 e precisione<\/h2>\n<p data-start=\"281\" data-end=\"727\">Per i portatori di apparecchi acustici, la facilit\u00e0 d \u201cuso \u00e8 importante almeno quanto la qualit\u00e0 del suono. Perch\u00e9 quanto \u00e8 bello avere il controllo della propria esperienza di ascolto, ovunque ci si trovi? Il <strong data-start=\"460\" data-end=\"484\">Connexx Smart Remote<\/strong> offre proprio questo: un semplice telecomando wireless che ti permette di regolare i tuoi apparecchi acustici in modo intuitivo e veloce. Niente menu complicati o piccoli pulsanti sull\u201d apparecchio acustico stesso, ma pulsanti fisici e chiari sul palmo della tua mano.   <\/p>\n<p data-start=\"729\" data-end=\"812\">Questo accessorio intelligente sblocca tutta la potenza dei tuoi apparecchi acustici.<\/p>\n<h2 data-start=\"814\" data-end=\"872\">Adatto per: Apparecchi acustici Audioservice G2, G3 e G4<\/h2>\n<p data-start=\"874\" data-end=\"1182\">Lo Smart Remote di Connexx \u00e8 stato progettato appositamente per essere utilizzato con gli apparecchi acustici <strong data-start=\"977\" data-end=\"1016\">Audioservice di generazione G2, G3 e G4<\/strong>. Il dispositivo funziona in modalit\u00e0 wireless e senza l \u201causilio di un\u201d app o di uno smartphone: \u00e8 quindi ideale per gli utenti che cercano semplicit\u00e0, affidabilit\u00e0 e controllo immediato. <\/p>\n<p data-start=\"1184\" data-end=\"1332\"><strong data-start=\"1184\" data-end=\"1199\">Importante:<\/strong><br data-start=\"1199\" data-end=\"1202\">Lo <strong data-start=\"1205\" data-end=\"1260\">Smart Remote non \u00e8 compatibile con gli<\/strong> apparecchi acustici <strong data-start=\"1205\" data-end=\"1260\">Audioservice G5<\/strong>. Per questi modelli sono disponibili altri accessori. <\/p>\n<h2 data-start=\"1334\" data-end=\"1379\">Cosa puoi aspettarti dallo Smart Remote?<\/h2>\n<p data-start=\"1381\" data-end=\"1483\">Con lo Smart Remote hai sempre accesso diretto alle funzioni pi\u00f9 importanti dei tuoi apparecchi acustici:<\/p>\n<ul data-start=\"1485\" data-end=\"1850\">\n<li data-start=\"1485\" data-end=\"1569\">\n<p data-start=\"1487\" data-end=\"1569\">Controllo del volume: aumenta o diminuisci facilmente il volume per ogni orecchio o contemporaneamente.<\/p>\n<\/li>\n<li data-start=\"1570\" data-end=\"1729\">\n<p data-start=\"1572\" data-end=\"1729\">Commutazione dei programmi: passa facilmente da un programma di ascolto all&#8217;altro (ad esempio per stanze silenziose, conversazioni di gruppo o ambienti esterni).<\/p>\n<\/li>\n<li data-start=\"1730\" data-end=\"1850\">\n<p data-start=\"1732\" data-end=\"1850\">Feedback chiaro: un indicatore visivo a LED conferma ogni azione, in modo che tu sappia che i tuoi apparecchi acustici stanno rispondendo.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1852\" data-end=\"2058\">Il telecomando funziona a batteria e ha un design compatto e leggero che si adatta comodamente alla mano. I pulsanti sono facili da sentire, anche per le persone con scarsa abilit\u00e0 motoria o con una vista ridotta. <\/p>\n<h2 data-start=\"2060\" data-end=\"2091\">Efficiente dal punto di vista energetico e affidabile<\/h2>\n<p data-start=\"2093\" data-end=\"2302\">Lo Smart Remote \u00e8 stato progettato pensando alla durata e alla facilit\u00e0 d&#8217;uso. Grazie al basso consumo energetico, la batteria dura a lungo e la connessione agli apparecchi acustici rimane stabile e priva di interferenze. <\/p>\n<p data-start=\"2304\" data-end=\"2494\">Non c \u201c\u00e8 bisogno di ricollegare spesso il telecomando: una volta collegato, continua a funzionare in modo affidabile. Questo lo rende uno strumento particolarmente adatto all\u201d uso quotidiano. <\/p>\n<h2 data-start=\"2496\" data-end=\"2541\">Per chi \u00e8 ideale questo telecomando?<\/h2>\n<p data-start=\"2543\" data-end=\"2583\">Il telecomando intelligente Connexx \u00e8 perfetto per:<\/p>\n<ul data-start=\"2585\" data-end=\"2961\">\n<li data-start=\"2585\" data-end=\"2646\">\n<p data-start=\"2587\" data-end=\"2646\">Utenti di <strong data-start=\"2602\" data-end=\"2646\">apparecchi acustici Audioservice G2, G3 o G4<\/strong><\/p>\n<\/li>\n<li data-start=\"2647\" data-end=\"2720\">\n<p data-start=\"2649\" data-end=\"2720\">Persone che <strong data-start=\"2660\" data-end=\"2679\">non<\/strong> usano <strong data-start=\"2660\" data-end=\"2679\">uno smartphone<\/strong> o che preferiscono non installare un&#8217;applicazione<\/p>\n<\/li>\n<li data-start=\"2721\" data-end=\"2796\">\n<p data-start=\"2723\" data-end=\"2796\">Utenti che amano i pulsanti fisici invece dei touch screen<\/p>\n<\/li>\n<li data-start=\"2797\" data-end=\"2891\">\n<p data-start=\"2799\" data-end=\"2891\">Gli individui che vogliono mantenere il controllo sulle impostazioni di ascolto in diversi ambienti<\/p>\n<\/li>\n<li data-start=\"2892\" data-end=\"2961\">\n<p data-start=\"2894\" data-end=\"2961\">Utenti anziani o persone con disabilit\u00e0 visive o motorie<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"2963\" data-end=\"2986\">I vantaggi in sintesi<\/h2>\n<ul data-start=\"2988\" data-end=\"3322\">\n<li data-start=\"2988\" data-end=\"3032\">\n<p data-start=\"2990\" data-end=\"3032\">Compatibile con Audioservice G2, G3 e G4<\/p>\n<\/li>\n<li data-start=\"3033\" data-end=\"3073\">\n<p data-start=\"3035\" data-end=\"3073\">Non adatto agli apparecchi acustici G5<\/p>\n<\/li>\n<li data-start=\"3074\" data-end=\"3125\">\n<p data-start=\"3076\" data-end=\"3125\">Facile da usare, senza app o smartphone<\/p>\n<\/li>\n<li data-start=\"3126\" data-end=\"3171\">\n<p data-start=\"3128\" data-end=\"3171\">Regola facilmente il volume e i programmi<\/p>\n<\/li>\n<li data-start=\"3172\" data-end=\"3204\">\n<p data-start=\"3174\" data-end=\"3204\">Compatto e leggero<\/p>\n<\/li>\n<li data-start=\"3205\" data-end=\"3253\">\n<p data-start=\"3207\" data-end=\"3253\">Conferma visiva immediata delle impostazioni<\/p>\n<\/li>\n<li data-start=\"3254\" data-end=\"3290\">\n<p data-start=\"3256\" data-end=\"3290\">Connessione wireless affidabile<\/p>\n<\/li>\n<li data-start=\"3291\" data-end=\"3322\">\n<p data-start=\"3293\" data-end=\"3322\">Ideale per l&#8217;uso quotidiano<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"3324\" data-end=\"3355\">Cosa c&#8217;\u00e8 nella confezione?<\/h2>\n<ul data-start=\"3357\" data-end=\"3474\">\n<li data-start=\"3357\" data-end=\"3399\">\n<p data-start=\"3359\" data-end=\"3399\">Telecomando Connexx Smart Remote<\/p>\n<\/li>\n<li data-start=\"3400\" data-end=\"3422\">\n<p data-start=\"3402\" data-end=\"3422\">Manuale d&#8217;uso<\/p>\n<\/li>\n<li data-start=\"3423\" data-end=\"3474\">\n<p data-start=\"3425\" data-end=\"3474\">Batteria inclusa<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"3476\" data-end=\"3518\">Ottieni il massimo dai tuoi apparecchi acustici<\/h2>\n<p data-start=\"3520\" data-end=\"3834\">Con il <strong data-start=\"3527\" data-end=\"3551\">telecomando intelligente Connexx<\/strong> puoi controllare i tuoi apparecchi acustici Audio Service a modo tuo, senza problemi. Che tu sia a casa, in viaggio o seduto in un ristorante affollato, il controllo \u00e8 tuo. Questo telecomando \u00e8 il complemento perfetto per i tuoi apparecchi acustici, soprattutto se la comodit\u00e0 e l&#8217;indipendenza sono importanti per te.  <\/p>\n<p data-start=\"3836\" data-end=\"3975\">Cerchi una soluzione pratica e affidabile per controllare i tuoi apparecchi acustici? Allora il telecomando intelligente Connexx \u00e8 proprio quello che fa per te. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Connexx Smart Remote - Controlla i tuoi apparecchi acustici con facilit\u00e0 e precisione Per i portatori di apparecchi acustici, la facilit\u00e0 d \u201cuso \u00e8 importante almeno quanto la qualit\u00e0 del suono. Perch\u00e9 quanto \u00e8 bello avere il controllo della propria esperienza di ascolto, ovunque ci si trovi? Il Connexx Smart Remote offre proprio questo: un &hellip; <\/p>\n","protected":false},"featured_media":144179,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[8250,7662],"product_tag":[],"class_list":["post-144175","product","type-product","status-publish","has-post-thumbnail","product_cat-controlli-remoti","product_cat-elettronica","grid-sizer","latest_post","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Servizio audioConnexx Smart Remote | Horend Goed Audiciens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servizio audioConnexx Smart Remote\" \/>\n<meta property=\"og:description\" content=\"Connexx Smart Remote - Controlla i tuoi apparecchi acustici con facilit\u00e0 e precisione Per i portatori di apparecchi acustici, la facilit\u00e0 d \u201cuso \u00e8 importante almeno quanto la qualit\u00e0 del suono. Perch\u00e9 quanto \u00e8 bello avere il controllo della propria esperienza di ascolto, ovunque ci si trovi? Il Connexx Smart Remote offre proprio questo: un &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T09:09:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2023\/09\/21f2-8e07-47d9-a8bf-40b509f78600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"882\" \/>\n\t<meta property=\"og:image:height\" content=\"882\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/controlli-remoti\\\/telecomando-intelligente-connexx\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/controlli-remoti\\\/telecomando-intelligente-connexx\\\/\",\"name\":\"Servizio audioConnexx Smart Remote | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/controlli-remoti\\\/telecomando-intelligente-connexx\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/controlli-remoti\\\/telecomando-intelligente-connexx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/21f2-8e07-47d9-a8bf-40b509f78600.jpg\",\"datePublished\":\"2023-09-21T13:28:35+00:00\",\"dateModified\":\"2025-09-15T09:09:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/controlli-remoti\\\/telecomando-intelligente-connexx\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/controlli-remoti\\\/telecomando-intelligente-connexx\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/controlli-remoti\\\/telecomando-intelligente-connexx\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/21f2-8e07-47d9-a8bf-40b509f78600.jpg\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/21f2-8e07-47d9-a8bf-40b509f78600.jpg\",\"width\":882,\"height\":882},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/controlli-remoti\\\/telecomando-intelligente-connexx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/negozio\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Servizio audioConnexx Smart Remote\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Servizio audioConnexx Smart Remote | Horend Goed Audiciens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/","og_locale":"it_IT","og_type":"article","og_title":"Servizio audioConnexx Smart Remote","og_description":"Connexx Smart Remote - Controlla i tuoi apparecchi acustici con facilit\u00e0 e precisione Per i portatori di apparecchi acustici, la facilit\u00e0 d \u201cuso \u00e8 importante almeno quanto la qualit\u00e0 del suono. Perch\u00e9 quanto \u00e8 bello avere il controllo della propria esperienza di ascolto, ovunque ci si trovi? Il Connexx Smart Remote offre proprio questo: un &hellip;","og_url":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","article_modified_time":"2025-09-15T09:09:04+00:00","og_image":[{"width":882,"height":882,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2023\/09\/21f2-8e07-47d9-a8bf-40b509f78600.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/","url":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/","name":"Servizio audioConnexx Smart Remote | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2023\/09\/21f2-8e07-47d9-a8bf-40b509f78600.jpg","datePublished":"2023-09-21T13:28:35+00:00","dateModified":"2025-09-15T09:09:04+00:00","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2023\/09\/21f2-8e07-47d9-a8bf-40b509f78600.jpg","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2023\/09\/21f2-8e07-47d9-a8bf-40b509f78600.jpg","width":882,"height":882},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/controlli-remoti\/telecomando-intelligente-connexx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/www.horendgoed.nl\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.horendgoed.nl\/it\/negozio\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Servizio audioConnexx Smart Remote"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/it\/#website","url":"https:\/\/www.horendgoed.nl\/it\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/it\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.horendgoed.nl\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/product\/144175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/media\/144179"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/media?parent=144175"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/product_brand?post=144175"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/product_cat?post=144175"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/product_tag?post=144175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}