{"id":271235,"date":"2025-12-05T11:20:13","date_gmt":"2025-12-05T10:20:13","guid":{"rendered":"https:\/\/www.horendgoed.nl\/shop\/senza-categoria\/bernafon-minifit-bass-dome\/"},"modified":"2025-12-05T11:20:13","modified_gmt":"2025-12-05T10:20:13","slug":"bernafon-minifit-bass-dome","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/","title":{"rendered":"Bernafon minifit Bass Dome"},"content":{"rendered":"<p data-start=\"74\" data-end=\"153\"><strong data-start=\"74\" data-end=\"153\">Bernafon MiniFit Bass Dome - Suono confortevole con una risposta dei bassi estremamente calda<\/strong><\/p>\n<p data-start=\"155\" data-end=\"649\">Quando si indossano gli apparecchi acustici, non \u00e8 importante solo la tecnologia, ma anche la giusta vestibilit\u00e0 e l&#8217;esperienza sonora. Una parte importante di questo aspetto \u00e8 la cupola: la punta in silicone morbido che viene posizionata sopra l&#8217;altoparlante e si inserisce nel canale uditivo. La cupola <strong data-start=\"419\" data-end=\"449\">Bernafon MiniFit Bass Dome<\/strong> ha una funzione ben precisa: migliorare i bassi caldi e corposi, in modo che il suono risulti pi\u00f9 naturale, ricco e piacevole. Questa cupola assicura che gli apparecchi acustici Bernafon MiniFit funzionino al meglio.   <\/p>\n<p data-start=\"651\" data-end=\"962\">Scegliere le MiniFit Bass Dome significa scegliere sia il comfort che il miglioramento del suono. Il materiale \u00e8 morbido nell&#8217;orecchio e sigilla bene, riducendo la dispersione del suono e rendendo i bassi pi\u00f9 udibili. Questo rende le conversazioni, ma soprattutto la musica e i suoni ambientali, pi\u00f9 realistici e meno acuti.  <\/p>\n<hr data-start=\"964\" data-end=\"967\">\n<h3 data-start=\"969\" data-end=\"1023\">Cosa rende speciale il Bernafon MiniFit Bass Dome?<\/h3>\n<p data-start=\"1025\" data-end=\"1441\">Il MiniFit Bass Dome \u00e8 progettato per rendere i toni profondi pi\u00f9 caldi e pieni. Questo risultato \u00e8 ottenuto grazie a una tenuta pi\u00f9 stretta nel canale uditivo, che consente una minore fuoriuscita del suono. Il risultato \u00e8 un suono naturale, senza che gli acuti perdano dettaglio. Inoltre, l&#8217;aderenza salda ma morbida garantisce che la cupola rimanga al suo posto e riduce il rischio di feedback o fischi.   <\/p>\n<p data-start=\"1443\" data-end=\"1774\">Anche il comfort gioca un ruolo fondamentale. Le cupole sono realizzate in silicone morbido e delicato sulla pelle e sono adatte a un uso prolungato senza irritazioni. La cupola si muove leggermente con il canale uditivo e non risulta dura o opprimente. Questo rende il prodotto adatto all&#8217;uso quotidiano, anche per gli utenti con orecchie sensibili.   <\/p>\n<hr data-start=\"1776\" data-end=\"1779\">\n<h3 data-start=\"1781\" data-end=\"1830\">Adatto agli apparecchi acustici Bernafon MiniFit<\/h3>\n<p data-start=\"1832\" data-end=\"2140\">Il MiniFit Bass Dome \u00e8 realizzato con un attacco specifico per gli apparecchi acustici Bernafon con altoparlanti MiniFit. Questo garantisce una connessione perfetta, senza allentamenti e senza il rischio che si allentino. I tappi si agganciano semplicemente all&#8217;altoparlante, permettendoti di sostituirli da solo senza bisogno di attrezzi.  <\/p>\n<hr data-start=\"2142\" data-end=\"2145\">\n<h3 data-start=\"2147\" data-end=\"2181\">Disponibile in diverse misure<\/h3>\n<p data-start=\"2183\" data-end=\"2261\">Poich\u00e9 ogni canale uditivo \u00e8 diverso, il MiniFit Bass Dome \u00e8 disponibile in quattro misure:<\/p>\n<ul data-start=\"2263\" data-end=\"2375\">\n<li data-start=\"2263\" data-end=\"2277\">\n<p data-start=\"2265\" data-end=\"2277\">6 mm (piccolo)<\/p>\n<\/li>\n<li data-start=\"2278\" data-end=\"2293\">\n<p data-start=\"2280\" data-end=\"2293\">8 mm (medio)<\/p>\n<\/li>\n<li data-start=\"2294\" data-end=\"2326\">\n<p data-start=\"2296\" data-end=\"2326\">10 mm (grande, pi\u00f9 sigillante)<\/p>\n<\/li>\n<li data-start=\"2327\" data-end=\"2375\">\n<p data-start=\"2329\" data-end=\"2375\">12 mm (chiusura extra, massima riproduzione dei bassi)<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2377\" data-end=\"2581\">Un formato pi\u00f9 grande di solito offre una migliore tenuta e quindi pi\u00f9 bassi e meno rumore ambientale. Una misura pi\u00f9 piccola a volte risulta pi\u00f9 ariosa. La misura giusta dipende dall&#8217;orecchio e dal suono desiderato.  <\/p>\n<hr data-start=\"2583\" data-end=\"2586\">\n<h3 data-start=\"2588\" data-end=\"2631\">Scelta tra bocchetta singola e doppia<\/h3>\n<p data-start=\"2633\" data-end=\"2805\">La cupola per bassi MiniFit \u00e8 disponibile con <strong data-start=\"2674\" data-end=\"2706\">una presa d&#8217;aria singola<\/strong> e una <strong data-start=\"2710\" data-end=\"2743\">doppia<\/strong>. Lo sfiato si riferisce al piccolo canale d&#8217;aria all&#8217;interno della cupola. <\/p>\n<ul data-start=\"2807\" data-end=\"3149\">\n<li data-start=\"2807\" data-end=\"2973\">\n<p data-start=\"2809\" data-end=\"2973\"><strong data-start=\"2809\" data-end=\"2824\">Bocchetta singola<\/strong>: offre una maggiore tenuta per un suono pi\u00f9 caldo e bassi pi\u00f9 intensi. Adatto a chi vuole attutire i rumori provenienti dall&#8217;esterno o cerca una riproduzione musicale pi\u00f9 completa. <\/p>\n<\/li>\n<li data-start=\"2974\" data-end=\"3149\">\n<p data-start=\"2976\" data-end=\"3149\"><strong data-start=\"2976\" data-end=\"2991\">Doppio sfiato<\/strong>: permette il passaggio di una quantit\u00e0 d&#8217;aria leggermente maggiore, rendendo la voce pi\u00f9 naturale e riducendo la sensazione di pressione. Spesso \u00e8 pi\u00f9 comodo per l&#8217;uso quotidiano. <\/p>\n<\/li>\n<\/ul>\n<p data-start=\"3151\" data-end=\"3297\">La scelta dipende dalle preferenze personali: pi\u00f9 chiusura per i bassi e meno rumore, oppure pi\u00f9 ventilazione per una voce pi\u00f9 naturale.<\/p>\n<hr data-start=\"3299\" data-end=\"3302\">\n<h3 data-start=\"3304\" data-end=\"3326\">Comfort e igiene<\/h3>\n<p data-start=\"3328\" data-end=\"3576\">Poich\u00e9 le cupole vengono indossate quotidianamente, l&#8217;igiene \u00e8 importante. Ti consigliamo di pulirle regolarmente e di sostituirle mensilmente in caso di uso intensivo. In questo modo si evita l&#8217;intasamento da parte del cerume e si garantisce che la qualit\u00e0 del suono rimanga ottimale.  <\/p>\n<hr data-start=\"3578\" data-end=\"3581\">\n<h3 data-start=\"3583\" data-end=\"3629\">A chi \u00e8 adatto il MiniFit Bass Dome?<\/h3>\n<ul data-start=\"3631\" data-end=\"3913\">\n<li data-start=\"3631\" data-end=\"3681\">\n<p data-start=\"3633\" data-end=\"3681\">Per i portatori di apparecchi acustici Bernafon MiniFit<\/p>\n<\/li>\n<li data-start=\"3682\" data-end=\"3735\">\n<p data-start=\"3684\" data-end=\"3735\">Per chi desidera una riproduzione del suono calda e naturale<\/p>\n<\/li>\n<li data-start=\"3736\" data-end=\"3794\">\n<p data-start=\"3738\" data-end=\"3794\">Per gli utenti che hanno difficolt\u00e0 a capire nel rumore<\/p>\n<\/li>\n<li data-start=\"3795\" data-end=\"3856\">\n<p data-start=\"3797\" data-end=\"3856\">Per tutti coloro che desiderano pi\u00f9 bassi e meno nitidezza nel suono<\/p>\n<\/li>\n<li data-start=\"3857\" data-end=\"3913\">\n<p data-start=\"3859\" data-end=\"3913\">Per chi apprezza il comfort e la vestibilit\u00e0<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"3915\" data-end=\"3918\">\n<h3 data-start=\"3920\" data-end=\"3986\">Perch\u00e9 scegliere Bernafon MiniFit Bass Dome a Horend Goed?<\/h3>\n<p data-start=\"3988\" data-end=\"4326\">Noi di Horend Goed consigliamo quotidianamente agli utenti il comfort e la qualit\u00e0 del suono. Il MiniFit Bass Dome \u00e8 una parte importante di un apparecchio acustico ben calibrato. Forniamo diverse dimensioni e opzioni di ventilazione, in modo che tu possa sempre fare una scelta appropriata. Le nostre cupole sono disponibili in magazzino e sono confezionate in modo professionale.   <\/p>\n<hr data-start=\"4328\" data-end=\"4331\">\n<p data-start=\"4333\" data-end=\"4550\" data-is-last-node=\"\" data-is-only-node=\"\">Con il <strong data-start=\"4340\" data-end=\"4370\">MiniFit Bass Dome di Bernafon<\/strong>, ottieni un piccolo componente che fa una grande differenza. Scegli la dimensione e la portata che preferisci e prova un&#8217;esperienza di ascolto pi\u00f9 calda, chiara e naturale con i tuoi apparecchi acustici. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bernafon MiniFit Bass Dome - Suono confortevole con una risposta dei bassi estremamente calda Quando si indossano gli apparecchi acustici, non \u00e8 importante solo la tecnologia, ma anche la giusta vestibilit\u00e0 e l&#8217;esperienza sonora. Una parte importante di questo aspetto \u00e8 la cupola: la punta in silicone morbido che viene posizionata sopra l&#8217;altoparlante e si &hellip; <\/p>\n","protected":false},"featured_media":271236,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[8228],"product_tag":[13901],"class_list":["post-271235","product","type-product","status-publish","has-post-thumbnail","product_cat-cupole","product_tag-bernafon-it","grid-sizer","latest_post","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bernafon minifit Bass Dome | Horend Goed Audiciens<\/title>\n<meta name=\"description\" content=\"Le MiniFit Bass Domes di Bernafon garantiscono un suono caldo e una vestibilit\u00e0 confortevole. Sono disponibili in diverse misure e con sfiato singolo o doppio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bernafon minifit Bass Dome\" \/>\n<meta property=\"og:description\" content=\"Le MiniFit Bass Domes di Bernafon garantiscono un suono caldo e una vestibilit\u00e0 confortevole. Sono disponibili in diverse misure e con sfiato singolo o doppio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/12\/Horend-Goed-Bernafon-minfit-bass-dome-8-mm-single-vent.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/cupole\\\/bernafon-minifit-bass-dome\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/cupole\\\/bernafon-minifit-bass-dome\\\/\",\"name\":\"Bernafon minifit Bass Dome | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/cupole\\\/bernafon-minifit-bass-dome\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/cupole\\\/bernafon-minifit-bass-dome\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Horend-Goed-Bernafon-minfit-bass-dome-8-mm-single-vent.jpg\",\"datePublished\":\"2025-12-05T10:20:13+00:00\",\"description\":\"Le MiniFit Bass Domes di Bernafon garantiscono un suono caldo e una vestibilit\u00e0 confortevole. Sono disponibili in diverse misure e con sfiato singolo o doppio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/cupole\\\/bernafon-minifit-bass-dome\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/cupole\\\/bernafon-minifit-bass-dome\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/cupole\\\/bernafon-minifit-bass-dome\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Horend-Goed-Bernafon-minfit-bass-dome-8-mm-single-vent.jpg\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Horend-Goed-Bernafon-minfit-bass-dome-8-mm-single-vent.jpg\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/shop\\\/accessori\\\/cupole\\\/bernafon-minifit-bass-dome\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/negozio\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bernafon minifit Bass Dome\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bernafon minifit Bass Dome | Horend Goed Audiciens","description":"Le MiniFit Bass Domes di Bernafon garantiscono un suono caldo e una vestibilit\u00e0 confortevole. Sono disponibili in diverse misure e con sfiato singolo o doppio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/","og_locale":"it_IT","og_type":"article","og_title":"Bernafon minifit Bass Dome","og_description":"Le MiniFit Bass Domes di Bernafon garantiscono un suono caldo e una vestibilit\u00e0 confortevole. Sono disponibili in diverse misure e con sfiato singolo o doppio.","og_url":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","og_image":[{"width":1600,"height":1600,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/12\/Horend-Goed-Bernafon-minfit-bass-dome-8-mm-single-vent.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/","url":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/","name":"Bernafon minifit Bass Dome | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/12\/Horend-Goed-Bernafon-minfit-bass-dome-8-mm-single-vent.jpg","datePublished":"2025-12-05T10:20:13+00:00","description":"Le MiniFit Bass Domes di Bernafon garantiscono un suono caldo e una vestibilit\u00e0 confortevole. Sono disponibili in diverse misure e con sfiato singolo o doppio.","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/12\/Horend-Goed-Bernafon-minfit-bass-dome-8-mm-single-vent.jpg","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/12\/Horend-Goed-Bernafon-minfit-bass-dome-8-mm-single-vent.jpg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/it\/shop\/accessori\/cupole\/bernafon-minifit-bass-dome\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/www.horendgoed.nl\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.horendgoed.nl\/it\/negozio\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Bernafon minifit Bass Dome"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/it\/#website","url":"https:\/\/www.horendgoed.nl\/it\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/it\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.horendgoed.nl\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/product\/271235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/media\/271236"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/media?parent=271235"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/product_brand?post=271235"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/product_cat?post=271235"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/it\/wp-json\/wp\/v2\/product_tag?post=271235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}