{"id":202689,"date":"2022-12-13T13:23:08","date_gmt":"2022-12-13T13:23:08","guid":{"rendered":"https:\/\/www.horendgoed.nl\/shop\/sem%20categoria\/oticon-griptip-pequeno-com-ventilacao-direita\/"},"modified":"2025-07-04T08:25:40","modified_gmt":"2025-07-04T06:25:40","slug":"oticon-griptip-pequeno-com-ventilacao-direita","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/","title":{"rendered":"Oticon GripTip Pequeno com ventila\u00e7\u00e3o Direita"},"content":{"rendered":"<p>Tens um aparelho auditivo Oticon com altifalante? Ent\u00e3o podes encomendar os teus pr\u00f3prios materiais em Horend Goed. A Oticon tem v\u00e1rias c\u00fapulas ou pontas universais.  <\/p>\n<p>Certifica-te sempre de que substituis a c\u00fapula ou a ponta pelo mesmo modelo. Isto \u00e9 importante para a coloca\u00e7\u00e3o no teu canal auditivo, para o ajuste do aparelho auditivo e para evitar que a ponta se solte facilmente do altifalante num momento indesejado. <\/p>\n<p>A Oticon Grip Tip est\u00e1 dispon\u00edvel em v\u00e1rios tamanhos e com ou sem ventila\u00e7\u00e3o.<\/p>\n<p>O Grip Tip \u00e9 fornecido em pares, \u00e0 esquerda ou \u00e0 direita.<\/p>\n<p>Como \u00e9 que substituis uma Oticon Grip Tip?<\/p>\n<p>Utiliza um len\u00e7o de papel para remover o Oticon Grip Tip antigo. Certifica-te de que utilizas o len\u00e7o de papel para agarrar firmemente a Grip Tip.  Com um movimento de torcer\/puxar, podes remover a Grip Tip antiga.<br \/>\nObserva bem o filtro, porque se o filtro estiver sujo ou entupido, \u00e9 melhor substitu\u00ed-lo imediatamente tamb\u00e9m.<br \/>\nColoca uma nova Oticon Grip Tip no altifalante. Nota a diferen\u00e7a entre esquerda e direita! Certifica-te de que pressionas a Grip Tip com firmeza at\u00e9 n\u00e3o poder ir mais longe. Isto evitar\u00e1 que a Grip Tip se solte do altifalante e fique no teu canal auditivo.   <\/p>\n<p>Esta ponta de aperto da Oticon s\u00f3 \u00e9 adequada para altifalantes MiniFit e para os altifalantes modelo 100 da Oticon.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tens um aparelho auditivo Oticon com altifalante? Ent\u00e3o podes encomendar os teus pr\u00f3prios materiais em Horend Goed. A Oticon tem v\u00e1rias c\u00fapulas ou pontas universais. Certifica-te sempre de que substituis a c\u00fapula ou a ponta pelo mesmo modelo. Isto \u00e9 importante para a coloca\u00e7\u00e3o no teu canal auditivo, para o ajuste do aparelho auditivo e &hellip; <\/p>\n","protected":false},"featured_media":202692,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[14711,14867],"product_tag":[14831],"class_list":["post-202689","product","type-product","status-publish","has-post-thumbnail","product_cat-acessorios","product_cat-cupulas-pt-pt","product_tag-oticon-pt-pt","grid-sizer","latest_post","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Oticon GripTip Pequeno com ventila\u00e7\u00e3o Direita | Horend Goed Audiciens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oticon GripTip Pequeno com ventila\u00e7\u00e3o Direita\" \/>\n<meta property=\"og:description\" content=\"Tens um aparelho auditivo Oticon com altifalante? Ent\u00e3o podes encomendar os teus pr\u00f3prios materiais em Horend Goed. A Oticon tem v\u00e1rias c\u00fapulas ou pontas universais. Certifica-te sempre de que substituis a c\u00fapula ou a ponta pelo mesmo modelo. Isto \u00e9 importante para a coloca\u00e7\u00e3o no teu canal auditivo, para o ajuste do aparelho auditivo e &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-04T06:25:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/06af-c5f3-4f16-9ae0-c51af8f30b54-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/oticon-griptip-pequeno-com-ventilacao-direita\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/oticon-griptip-pequeno-com-ventilacao-direita\\\/\",\"name\":\"Oticon GripTip Pequeno com ventila\u00e7\u00e3o Direita | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/oticon-griptip-pequeno-com-ventilacao-direita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/oticon-griptip-pequeno-com-ventilacao-direita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/06af-c5f3-4f16-9ae0-c51af8f30b54-2.jpg\",\"datePublished\":\"2022-12-13T13:23:08+00:00\",\"dateModified\":\"2025-07-04T06:25:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/oticon-griptip-pequeno-com-ventilacao-direita\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/oticon-griptip-pequeno-com-ventilacao-direita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/oticon-griptip-pequeno-com-ventilacao-direita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/06af-c5f3-4f16-9ae0-c51af8f30b54-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/06af-c5f3-4f16-9ae0-c51af8f30b54-2.jpg\",\"width\":550,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/oticon-griptip-pequeno-com-ventilacao-direita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/compra\\\/produtos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oticon GripTip Pequeno com ventila\u00e7\u00e3o Direita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Oticon GripTip Pequeno com ventila\u00e7\u00e3o Direita | Horend Goed Audiciens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/","og_locale":"pt_PT","og_type":"article","og_title":"Oticon GripTip Pequeno com ventila\u00e7\u00e3o Direita","og_description":"Tens um aparelho auditivo Oticon com altifalante? Ent\u00e3o podes encomendar os teus pr\u00f3prios materiais em Horend Goed. A Oticon tem v\u00e1rias c\u00fapulas ou pontas universais. Certifica-te sempre de que substituis a c\u00fapula ou a ponta pelo mesmo modelo. Isto \u00e9 importante para a coloca\u00e7\u00e3o no teu canal auditivo, para o ajuste do aparelho auditivo e &hellip;","og_url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","article_modified_time":"2025-07-04T06:25:40+00:00","og_image":[{"width":550,"height":594,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/06af-c5f3-4f16-9ae0-c51af8f30b54-2.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/","url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/","name":"Oticon GripTip Pequeno com ventila\u00e7\u00e3o Direita | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/06af-c5f3-4f16-9ae0-c51af8f30b54-2.jpg","datePublished":"2022-12-13T13:23:08+00:00","dateModified":"2025-07-04T06:25:40+00:00","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/06af-c5f3-4f16-9ae0-c51af8f30b54-2.jpg","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2022\/12\/06af-c5f3-4f16-9ae0-c51af8f30b54-2.jpg","width":550,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/oticon-griptip-pequeno-com-ventilacao-direita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/www.horendgoed.nl\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.horendgoed.nl\/pt-pt\/compra\/produtos\/"},{"@type":"ListItem","position":3,"name":"Oticon GripTip Pequeno com ventila\u00e7\u00e3o Direita"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product\/202689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media\/202692"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media?parent=202689"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=202689"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=202689"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=202689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}