{"id":205576,"date":"2024-03-14T14:17:04","date_gmt":"2024-03-14T14:17:04","guid":{"rendered":"https:\/\/www.horendgoed.nl\/shop\/sem%20categoria\/geemarc-sos-pendente-amplidect-595\/"},"modified":"2025-11-14T11:48:35","modified_gmt":"2025-11-14T10:48:35","slug":"geemarc-sos-pendente-amplidect-595","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/","title":{"rendered":"Geemarc SOS pendente Amplidect 595"},"content":{"rendered":"<h3>Aumenta a tua seguran\u00e7a e comodidade com o suspensor SOS Pro 595<\/h3>\n<p>No mundo moderno em que vivemos, a seguran\u00e7a \u00e9 uma prioridade m\u00e1xima. O <strong>pendente SOS Pro 595<\/strong> oferece uma solu\u00e7\u00e3o inovadora que aumenta significativamente a tua sensa\u00e7\u00e3o de seguran\u00e7a e comodidade. Concebido especificamente para os telefones da s\u00e9rie Geemarc Amplidect 595, este acess\u00f3rio indispens\u00e1vel permite aos utilizadores fazer chamadas em modo m\u00e3os-livres e atender chamadas em situa\u00e7\u00f5es de emerg\u00eancia, sem depender da unidade base ou do microtelefone.<\/p>\n<h4><strong>Fun\u00e7\u00e3o SOS simples e fi\u00e1vel<\/strong><\/h4>\n<p>Uma das principais carater\u00edsticas do pendente SOS Pro 595 \u00e9 a sua fun\u00e7\u00e3o SOS f\u00e1cil de utilizar. Com apenas um toque num bot\u00e3o, podes iniciar uma chamada de emerg\u00eancia para um m\u00e1ximo de quatro n\u00fameros predefinidos. Isto significa que a ajuda est\u00e1 sempre ao teu alcance, quer estejas em casa, no jardim ou na estrada. Esta funcionalidade garante que nunca te sintas sozinho, mesmo em situa\u00e7\u00f5es de emerg\u00eancia.<\/p>\n<h4><strong>Contacto direto com os teus entes queridos<\/strong><\/h4>\n<p>A consola SOS Pro 595 est\u00e1 equipada com dois bot\u00f5es program\u00e1veis, M1 e M2. Estes bot\u00f5es podem ser definidos para marcar diretamente os dois n\u00fameros mais frequentemente chamados. Quer precises de contactar rapidamente um membro da fam\u00edlia ou um amigo de confian\u00e7a, com o pendente SOS Pro 595, os teus entes queridos est\u00e3o apenas a um toque de bot\u00e3o. Isto oferece n\u00e3o s\u00f3 comodidade, mas tamb\u00e9m uma tranquilizadora sensa\u00e7\u00e3o de seguran\u00e7a.<\/p>\n<h4><strong>Sempre e em todo o lado na ponta dos teus dedos<\/strong><\/h4>\n<p>O pendente SOS Pro 595 n\u00e3o \u00e9 apenas uma extens\u00e3o do teu sistema telef\u00f3nico; \u00e9 um investimento na tua paz de esp\u00edrito. Quer estejas em casa, a trabalhar no jardim ou mesmo a uma maior dist\u00e2ncia da tua esta\u00e7\u00e3o de base, este pendente garante que a comunica\u00e7\u00e3o est\u00e1 sempre ao teu alcance. N\u00e3o tens de te preocupar em encontrar o teu telefone em caso de emerg\u00eancia, porque com o pendente SOS Pro 595, tens sempre uma linha direta de comunica\u00e7\u00e3o contigo.<\/p>\n<h4><strong>Design elegante e funcional<\/strong><\/h4>\n<p>Para al\u00e9m das suas vantagens funcionais, o pendente SOS Pro 595 tamb\u00e9m oferece um design elegante. \u00c9 leve e confort\u00e1vel de usar, pelo que n\u00e3o interfere com as tuas actividades di\u00e1rias. O pendente foi concebido a pensar no utilizador, o que significa que \u00e9 f\u00e1cil de operar mesmo para pessoas com compet\u00eancias t\u00e9cnicas limitadas.<\/p>\n<h4><strong>Adequado para v\u00e1rios modelos<\/strong><\/h4>\n<p>A botoeira SOS Pro 595 \u00e9 compat\u00edvel com v\u00e1rios modelos da s\u00e9rie Geemarc Amplidect 595, incluindo<\/p>\n<ul>\n<li>Amplidect 595 Fotografia<\/li>\n<li>Amplidect 595-2 Fotografia<\/li>\n<li>Amplidect 595 ULE<\/li>\n<li>Amplidect 595-2 ULE<\/li>\n<li>Amplidect Combi 595<\/li>\n<li>CL595<\/li>\n<li>Amplidect 595 U.L.E DOORBELL<\/li>\n<\/ul>\n<p>Esta vasta gama de compatibilidade garante que podes utilizar o pendente com o teu telem\u00f3vel existente sem te preocupares com problemas de compatibilidade.<\/p>\n<h4><strong>Investe na tua paz de esp\u00edrito<\/strong><\/h4>\n<p>Escolher o pendente SOS Pro 595 n\u00e3o \u00e9 apenas uma compra; \u00e9 um investimento na tua paz de esp\u00edrito e seguran\u00e7a. Num mundo onde as emerg\u00eancias podem surgir inesperadamente, este pendente oferece-te a garantia de que a ajuda est\u00e1 sempre ao teu alcance. Permite-te manter a independ\u00eancia e a confian\u00e7a, sabendo que podes sempre contactar com as pessoas que s\u00e3o importantes para ti.<\/p>\n<h4><strong>Encomenda hoje<\/strong><\/h4>\n<p>N\u00e3o esperes mais e aumenta a tua sensa\u00e7\u00e3o de seguran\u00e7a e comodidade com o <strong>pendente SOS Pro 595<\/strong>. Encomenda hoje e experimenta a diferen\u00e7a que este pendente inovador pode fazer na tua vida di\u00e1ria. Com o pendente SOS Pro 595, mant\u00e9ns-te sempre ligado, seguro e confiante.<\/p>\n<p>Escolhe o pendente SOS Pro 595 e investe na tua seguran\u00e7a e tranquilidade. Uma escolha inteligente para quem valoriza uma comunica\u00e7\u00e3o fi\u00e1vel e direta em qualquer situa\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aumenta a tua seguran\u00e7a e comodidade com o suspensor SOS Pro 595 No mundo moderno em que vivemos, a seguran\u00e7a \u00e9 uma prioridade m\u00e1xima. O pendente SOS Pro 595 oferece uma solu\u00e7\u00e3o inovadora que aumenta significativamente a tua sensa\u00e7\u00e3o de seguran\u00e7a e comodidade. Concebido especificamente para os telefones da s\u00e9rie Geemarc Amplidect 595, este acess\u00f3rio &hellip; <\/p>\n","protected":false},"featured_media":205579,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[14700,14838],"product_tag":[17044],"class_list":["post-205576","product","type-product","status-publish","has-post-thumbnail","product_cat-eletronica","product_cat-venda","product_tag-geemarc-pt-pt","grid-sizer","latest_post","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Geemarc SOS pendente Amplidect 595 | Horend Goed Audiciens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geemarc SOS pendente Amplidect 595\" \/>\n<meta property=\"og:description\" content=\"Aumenta a tua seguran\u00e7a e comodidade com o suspensor SOS Pro 595 No mundo moderno em que vivemos, a seguran\u00e7a \u00e9 uma prioridade m\u00e1xima. O pendente SOS Pro 595 oferece uma solu\u00e7\u00e3o inovadora que aumenta significativamente a tua sensa\u00e7\u00e3o de seguran\u00e7a e comodidade. Concebido especificamente para os telefones da s\u00e9rie Geemarc Amplidect 595, este acess\u00f3rio &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-14T10:48:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2024\/03\/OriginalImage-64.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/eletronica\\\/geemarc-sos-pendente-amplidect-595\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/eletronica\\\/geemarc-sos-pendente-amplidect-595\\\/\",\"name\":\"Geemarc SOS pendente Amplidect 595 | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/eletronica\\\/geemarc-sos-pendente-amplidect-595\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/eletronica\\\/geemarc-sos-pendente-amplidect-595\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/OriginalImage-64.jpeg\",\"datePublished\":\"2024-03-14T14:17:04+00:00\",\"dateModified\":\"2025-11-14T10:48:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/eletronica\\\/geemarc-sos-pendente-amplidect-595\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/eletronica\\\/geemarc-sos-pendente-amplidect-595\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/eletronica\\\/geemarc-sos-pendente-amplidect-595\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/OriginalImage-64.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/OriginalImage-64.jpeg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/eletronica\\\/geemarc-sos-pendente-amplidect-595\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/compra\\\/produtos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Geemarc SOS pendente Amplidect 595\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Geemarc SOS pendente Amplidect 595 | Horend Goed Audiciens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/","og_locale":"pt_PT","og_type":"article","og_title":"Geemarc SOS pendente Amplidect 595","og_description":"Aumenta a tua seguran\u00e7a e comodidade com o suspensor SOS Pro 595 No mundo moderno em que vivemos, a seguran\u00e7a \u00e9 uma prioridade m\u00e1xima. O pendente SOS Pro 595 oferece uma solu\u00e7\u00e3o inovadora que aumenta significativamente a tua sensa\u00e7\u00e3o de seguran\u00e7a e comodidade. Concebido especificamente para os telefones da s\u00e9rie Geemarc Amplidect 595, este acess\u00f3rio &hellip;","og_url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","article_modified_time":"2025-11-14T10:48:35+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2024\/03\/OriginalImage-64.jpeg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/","url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/","name":"Geemarc SOS pendente Amplidect 595 | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2024\/03\/OriginalImage-64.jpeg","datePublished":"2024-03-14T14:17:04+00:00","dateModified":"2025-11-14T10:48:35+00:00","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2024\/03\/OriginalImage-64.jpeg","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2024\/03\/OriginalImage-64.jpeg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/eletronica\/geemarc-sos-pendente-amplidect-595\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/www.horendgoed.nl\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.horendgoed.nl\/pt-pt\/compra\/produtos\/"},{"@type":"ListItem","position":3,"name":"Geemarc SOS pendente Amplidect 595"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product\/205576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media\/205579"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media?parent=205576"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=205576"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=205576"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=205576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}