{"id":205927,"date":"2023-09-21T13:28:35","date_gmt":"2023-09-21T13:28:35","guid":{"rendered":"https:\/\/www.horendgoed.nl\/shop\/sem%20categoria\/comando-inteligente-connexx\/"},"modified":"2025-09-15T11:09:02","modified_gmt":"2025-09-15T09:09:02","slug":"comando-inteligente-connexx","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/","title":{"rendered":"Servi\u00e7o de \u00e1udioConnexx Smart Remote"},"content":{"rendered":"<h2 data-start=\"207\" data-end=\"279\">Connexx Smart Remote - Controla os teus aparelhos auditivos com facilidade e precis\u00e3o<\/h2>\n<p data-start=\"281\" data-end=\"727\">Para os utilizadores de aparelhos auditivos, a facilidade de utiliza\u00e7\u00e3o \u00e9 pelo menos t\u00e3o importante como a qualidade do som. Porque n\u00e3o \u00e9 bom quando tens controlo sobre a tua experi\u00eancia auditiva, onde quer que estejas? O <strong data-start=\"460\" data-end=\"484\">Connexx Smart Remote<\/strong> oferece exatamente isso: um controlo remoto simples e sem fios que permite ajustar os teus aparelhos auditivos de forma intuitiva e r\u00e1pida. N\u00e3o h\u00e1 menus complicados ou bot\u00f5es pequenos no pr\u00f3prio aparelho auditivo, mas sim bot\u00f5es f\u00edsicos e claros na palma da tua m\u00e3o.   <\/p>\n<p data-start=\"729\" data-end=\"812\">Este acess\u00f3rio inteligente liberta toda a pot\u00eancia dos teus aparelhos auditivos.<\/p>\n<h2 data-start=\"814\" data-end=\"872\">Adequado para: Aparelhos auditivos Audioservice G2, G3 e G4<\/h2>\n<p data-start=\"874\" data-end=\"1182\">O Smart Remote da Connexx foi especificamente concebido para ser utilizado com os aparelhos auditivos <strong data-start=\"977\" data-end=\"1016\">Audioservice da gera\u00e7\u00e3o G2, G3 e G4<\/strong>. O dispositivo funciona sem fios e sem uma aplica\u00e7\u00e3o ou smartphone, o que o torna ideal para utilizadores que procuram simplicidade, fiabilidade e controlo imediato. <\/p>\n<p data-start=\"1184\" data-end=\"1332\"><strong data-start=\"1184\" data-end=\"1199\">Importante:<\/strong><br data-start=\"1199\" data-end=\"1202\">O <strong data-start=\"1205\" data-end=\"1260\">Smart Remote n\u00e3o \u00e9 compat\u00edvel com os<\/strong> aparelhos auditivos <strong data-start=\"1205\" data-end=\"1260\">Audioservice G5<\/strong>. Para estes modelos, est\u00e3o dispon\u00edveis outros acess\u00f3rios. <\/p>\n<h2 data-start=\"1334\" data-end=\"1379\">O que podes esperar do telecomando inteligente?<\/h2>\n<p data-start=\"1381\" data-end=\"1483\">Com o Smart Remote, tens sempre acesso direto \u00e0s fun\u00e7\u00f5es mais importantes dos teus aparelhos auditivos:<\/p>\n<ul data-start=\"1485\" data-end=\"1850\">\n<li data-start=\"1485\" data-end=\"1569\">\n<p data-start=\"1487\" data-end=\"1569\">Controlo de volume: aumenta ou diminui facilmente o volume por ouvido ou em simult\u00e2neo.<\/p>\n<\/li>\n<li data-start=\"1570\" data-end=\"1729\">\n<p data-start=\"1572\" data-end=\"1729\">Comuta\u00e7\u00e3o de programas: alterna sem esfor\u00e7o entre programas de audi\u00e7\u00e3o predefinidos (por exemplo, para salas silenciosas, conversas em grupo ou ambientes exteriores).<\/p>\n<\/li>\n<li data-start=\"1730\" data-end=\"1850\">\n<p data-start=\"1732\" data-end=\"1850\">Feedback claro: um indicador LED visual confirma cada a\u00e7\u00e3o, para que saibas que os teus aparelhos auditivos est\u00e3o a responder.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1852\" data-end=\"2058\">O controlo remoto funciona a pilhas e tem um design compacto e leve que se adapta confortavelmente \u00e0 m\u00e3o. Os bot\u00f5es s\u00e3o f\u00e1ceis de apalpar, mesmo para pessoas com menos capacidades motoras finas ou vis\u00e3o reduzida. <\/p>\n<h2 data-start=\"2060\" data-end=\"2091\">Eficiente em termos energ\u00e9ticos e fi\u00e1vel<\/h2>\n<p data-start=\"2093\" data-end=\"2302\">O Smart Remote foi concebido tendo em conta a durabilidade e a facilidade de utiliza\u00e7\u00e3o. Com o seu baixo consumo de energia, a pilha dura muito tempo e a liga\u00e7\u00e3o aos teus aparelhos auditivos mant\u00e9m-se est\u00e1vel e sem interfer\u00eancias. <\/p>\n<p data-start=\"2304\" data-end=\"2494\">N\u00e3o precisas de voltar a emparelhar o telecomando com frequ\u00eancia - uma vez ligado, continua a funcionar de forma fi\u00e1vel. Isto torna-o uma ferramenta particularmente adequada para o uso di\u00e1rio. <\/p>\n<h2 data-start=\"2496\" data-end=\"2541\">Para quem \u00e9 ideal este telecomando?<\/h2>\n<p data-start=\"2543\" data-end=\"2583\">O telecomando inteligente Connexx \u00e9 perfeito para:<\/p>\n<ul data-start=\"2585\" data-end=\"2961\">\n<li data-start=\"2585\" data-end=\"2646\">\n<p data-start=\"2587\" data-end=\"2646\">Utilizadores de <strong data-start=\"2602\" data-end=\"2646\">aparelhos auditivos Audioservice G2, G3 ou G4<\/strong><\/p>\n<\/li>\n<li data-start=\"2647\" data-end=\"2720\">\n<p data-start=\"2649\" data-end=\"2720\">Pessoas que n\u00e3o utilizam <strong data-start=\"2660\" data-end=\"2679\">um smartphone<\/strong> ou preferem n\u00e3o instalar uma aplica\u00e7\u00e3o<\/p>\n<\/li>\n<li data-start=\"2721\" data-end=\"2796\">\n<p data-start=\"2723\" data-end=\"2796\">Utilizadores que gostam de bot\u00f5es f\u00edsicos em vez de ecr\u00e3s t\u00e1cteis<\/p>\n<\/li>\n<li data-start=\"2797\" data-end=\"2891\">\n<p data-start=\"2799\" data-end=\"2891\">Indiv\u00edduos que pretendem manter o controlo sobre as suas defini\u00e7\u00f5es de audi\u00e7\u00e3o em diferentes ambientes<\/p>\n<\/li>\n<li data-start=\"2892\" data-end=\"2961\">\n<p data-start=\"2894\" data-end=\"2961\">Utilizadores idosos ou pessoas com defici\u00eancias visuais ou motoras<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"2963\" data-end=\"2986\">Resumo das vantagens<\/h2>\n<ul data-start=\"2988\" data-end=\"3322\">\n<li data-start=\"2988\" data-end=\"3032\">\n<p data-start=\"2990\" data-end=\"3032\">Compat\u00edvel com Audioservice G2, G3 e G4<\/p>\n<\/li>\n<li data-start=\"3033\" data-end=\"3073\">\n<p data-start=\"3035\" data-end=\"3073\">N\u00e3o \u00e9 adequado para aparelhos auditivos G5<\/p>\n<\/li>\n<li data-start=\"3074\" data-end=\"3125\">\n<p data-start=\"3076\" data-end=\"3125\">F\u00e1cil de utilizar, sem aplica\u00e7\u00e3o ou smartphone<\/p>\n<\/li>\n<li data-start=\"3126\" data-end=\"3171\">\n<p data-start=\"3128\" data-end=\"3171\">Ajusta facilmente o volume e os programas<\/p>\n<\/li>\n<li data-start=\"3172\" data-end=\"3204\">\n<p data-start=\"3174\" data-end=\"3204\">Compacto e leve<\/p>\n<\/li>\n<li data-start=\"3205\" data-end=\"3253\">\n<p data-start=\"3207\" data-end=\"3253\">Confirma\u00e7\u00e3o visual instant\u00e2nea das defini\u00e7\u00f5es<\/p>\n<\/li>\n<li data-start=\"3254\" data-end=\"3290\">\n<p data-start=\"3256\" data-end=\"3290\">Liga\u00e7\u00e3o sem fios fi\u00e1vel<\/p>\n<\/li>\n<li data-start=\"3291\" data-end=\"3322\">\n<p data-start=\"3293\" data-end=\"3322\">Ideal para uso di\u00e1rio<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"3324\" data-end=\"3355\">O que \u00e9 que tens na embalagem?<\/h2>\n<ul data-start=\"3357\" data-end=\"3474\">\n<li data-start=\"3357\" data-end=\"3399\">\n<p data-start=\"3359\" data-end=\"3399\">Controlo remoto Connexx Smart Remote<\/p>\n<\/li>\n<li data-start=\"3400\" data-end=\"3422\">\n<p data-start=\"3402\" data-end=\"3422\">Manual do utilizador<\/p>\n<\/li>\n<li data-start=\"3423\" data-end=\"3474\">\n<p data-start=\"3425\" data-end=\"3474\">Pilha inclu\u00edda<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"3476\" data-end=\"3518\">Tira o m\u00e1ximo partido dos teus aparelhos auditivos<\/h2>\n<p data-start=\"3520\" data-end=\"3834\">Com o <strong data-start=\"3527\" data-end=\"3551\">Connexx Smart Remote<\/strong>, controlas os teus aparelhos auditivos Audio Service \u00e0 tua maneira - sem complica\u00e7\u00f5es. Quer estejas em casa, na estrada ou sentado num restaurante movimentado: est\u00e1s no controlo. Este controlo remoto \u00e9 o complemento perfeito para os teus aparelhos auditivos, especialmente se a conveni\u00eancia e a independ\u00eancia s\u00e3o importantes para ti.  <\/p>\n<p data-start=\"3836\" data-end=\"3975\">Est\u00e1s \u00e0 procura de uma solu\u00e7\u00e3o pr\u00e1tica e fi\u00e1vel para controlar os teus aparelhos auditivos? Ent\u00e3o o Connexx Smart Remote \u00e9 exatamente o que precisas. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Connexx Smart Remote - Controla os teus aparelhos auditivos com facilidade e precis\u00e3o Para os utilizadores de aparelhos auditivos, a facilidade de utiliza\u00e7\u00e3o \u00e9 pelo menos t\u00e3o importante como a qualidade do som. Porque n\u00e3o \u00e9 bom quando tens controlo sobre a tua experi\u00eancia auditiva, onde quer que estejas? O Connexx Smart Remote oferece exatamente &hellip; <\/p>\n","protected":false},"featured_media":205928,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[14885,14700],"product_tag":[],"class_list":["post-205927","product","type-product","status-publish","has-post-thumbnail","product_cat-controlos-remotos","product_cat-eletronica","grid-sizer","latest_post","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Servi\u00e7o de \u00e1udioConnexx Smart Remote | Horend Goed Audiciens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servi\u00e7o de \u00e1udioConnexx Smart Remote\" \/>\n<meta property=\"og:description\" content=\"Connexx Smart Remote - Controla os teus aparelhos auditivos com facilidade e precis\u00e3o Para os utilizadores de aparelhos auditivos, a facilidade de utiliza\u00e7\u00e3o \u00e9 pelo menos t\u00e3o importante como a qualidade do som. Porque n\u00e3o \u00e9 bom quando tens controlo sobre a tua experi\u00eancia auditiva, onde quer que estejas? O Connexx Smart Remote oferece exatamente &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T09:09:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2023\/09\/21f2-8e07-47d9-a8bf-40b509f78600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"882\" \/>\n\t<meta property=\"og:image:height\" content=\"882\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/controlos-remotos\\\/comando-inteligente-connexx\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/controlos-remotos\\\/comando-inteligente-connexx\\\/\",\"name\":\"Servi\u00e7o de \u00e1udioConnexx Smart Remote | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/controlos-remotos\\\/comando-inteligente-connexx\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/controlos-remotos\\\/comando-inteligente-connexx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/21f2-8e07-47d9-a8bf-40b509f78600.jpg\",\"datePublished\":\"2023-09-21T13:28:35+00:00\",\"dateModified\":\"2025-09-15T09:09:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/controlos-remotos\\\/comando-inteligente-connexx\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/controlos-remotos\\\/comando-inteligente-connexx\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/controlos-remotos\\\/comando-inteligente-connexx\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/21f2-8e07-47d9-a8bf-40b509f78600.jpg\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/21f2-8e07-47d9-a8bf-40b509f78600.jpg\",\"width\":882,\"height\":882},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/controlos-remotos\\\/comando-inteligente-connexx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/compra\\\/produtos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Servi\u00e7o de \u00e1udioConnexx Smart Remote\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Servi\u00e7o de \u00e1udioConnexx Smart Remote | Horend Goed Audiciens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/","og_locale":"pt_PT","og_type":"article","og_title":"Servi\u00e7o de \u00e1udioConnexx Smart Remote","og_description":"Connexx Smart Remote - Controla os teus aparelhos auditivos com facilidade e precis\u00e3o Para os utilizadores de aparelhos auditivos, a facilidade de utiliza\u00e7\u00e3o \u00e9 pelo menos t\u00e3o importante como a qualidade do som. Porque n\u00e3o \u00e9 bom quando tens controlo sobre a tua experi\u00eancia auditiva, onde quer que estejas? O Connexx Smart Remote oferece exatamente &hellip;","og_url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","article_modified_time":"2025-09-15T09:09:02+00:00","og_image":[{"width":882,"height":882,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2023\/09\/21f2-8e07-47d9-a8bf-40b509f78600.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/","url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/","name":"Servi\u00e7o de \u00e1udioConnexx Smart Remote | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2023\/09\/21f2-8e07-47d9-a8bf-40b509f78600.jpg","datePublished":"2023-09-21T13:28:35+00:00","dateModified":"2025-09-15T09:09:02+00:00","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2023\/09\/21f2-8e07-47d9-a8bf-40b509f78600.jpg","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2023\/09\/21f2-8e07-47d9-a8bf-40b509f78600.jpg","width":882,"height":882},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/controlos-remotos\/comando-inteligente-connexx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/www.horendgoed.nl\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.horendgoed.nl\/pt-pt\/compra\/produtos\/"},{"@type":"ListItem","position":3,"name":"Servi\u00e7o de \u00e1udioConnexx Smart Remote"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product\/205927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media\/205928"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media?parent=205927"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=205927"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=205927"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=205927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}