{"id":208749,"date":"2025-04-04T19:45:31","date_gmt":"2025-04-04T17:45:31","guid":{"rendered":"https:\/\/www.horendgoed.nl\/shop\/sem%20categoria\/bateria-fysic-fm-7810-3-7v-1000mah\/"},"modified":"2025-07-29T14:23:44","modified_gmt":"2025-07-29T12:23:44","slug":"bateria-fysic-fm-7810-3-7v-1000mah","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/","title":{"rendered":"Bateria Fysic FM-7810 (3.7V, 1000mAh)"},"content":{"rendered":"<p data-start=\"218\" data-end=\"308\"><strong data-start=\"218\" data-end=\"308\">Bateria original para Fysic FM-7810 - 3.7V \/ 1000mAh - Energia fi\u00e1vel para todos os dias<\/strong><\/p>\n<p data-start=\"310\" data-end=\"731\">Um telem\u00f3vel fi\u00e1vel merece uma bateria fi\u00e1vel. A <strong data-start=\"369\" data-end=\"401\">bateria original Fysic FM-7810<\/strong> foi especialmente concebida para substituir a bateria inclu\u00edda no telem\u00f3vel s\u00e9nior com o mesmo nome. Com uma capacidade de <strong data-start=\"538\" data-end=\"549\">1000mAh<\/strong> e uma voltagem de <strong data-start=\"570\" data-end=\"582\">3,7 volts<\/strong>, esta bateria garante que o teu telem\u00f3vel volta a funcionar como deve ser - com muito tempo de conversa\u00e7\u00e3o, desempenho est\u00e1vel e um longo tempo de espera.  <\/p>\n<h3 data-start=\"733\" data-end=\"779\">Encaixa na perfei\u00e7\u00e3o, especialmente para o FM-7810<\/h3>\n<p data-start=\"781\" data-end=\"1171\">Esta bateria de substitui\u00e7\u00e3o corresponde exatamente ao design e aos pontos de liga\u00e7\u00e3o do telem\u00f3vel Fysic FM-7810. Como \u00e9 uma <strong data-start=\"914\" data-end=\"937\">pe\u00e7a original<\/strong>, tens a garantia de compatibilidade total, sem risco de mensagens de erro ou desempenho reduzido. N\u00e3o precisas de fazer quaisquer ajustes e a bateria \u00e9 f\u00e1cil de instalar - a sua substitui\u00e7\u00e3o demora apenas alguns segundos.  <\/p>\n<h3 data-start=\"1173\" data-end=\"1229\">Desempenho potente gra\u00e7as \u00e0 tecnologia de i\u00f5es de l\u00edtio<\/h3>\n<p data-start=\"1231\" data-end=\"1610\">Com uma <strong data-start=\"1239\" data-end=\"1258\">c\u00e9lula de i\u00f5es de l\u00edtio<\/strong>, esta bateria oferece um excelente equil\u00edbrio entre capacidade, peso e longevidade. Gra\u00e7as \u00e0 sua capacidade de <strong data-start=\"1351\" data-end=\"1362\">1000mAh<\/strong>, podes contar com um amplo tempo de utiliza\u00e7\u00e3o, tanto para chamadas como em espera. Concebida para uma utiliza\u00e7\u00e3o quotidiana, a bateria pode suportar dezenas de ciclos de carregamento sem perda significativa de capacidade.  <\/p>\n<p data-start=\"1612\" data-end=\"1913\">As baterias de i\u00f5es de l\u00edtio tamb\u00e9m s\u00e3o conhecidas pela sua baixa auto-descarga. Isto significa que a bateria mant\u00e9m a carga durante muito tempo, mesmo em per\u00edodos de baixa utiliza\u00e7\u00e3o. Ideal para idosos que n\u00e3o utilizam o telem\u00f3vel constantemente, mas querem que ele esteja pronto quando necess\u00e1rio.  <\/p>\n<h3 data-start=\"1915\" data-end=\"1946\">F\u00e1cil de substituir por ti pr\u00f3prio<\/h3>\n<p data-start=\"1948\" data-end=\"2303\">A substitui\u00e7\u00e3o da bateria do Fysic FM-7810 \u00e9 f\u00e1cil e n\u00e3o requer conhecimentos t\u00e9cnicos. Remove a parte de tr\u00e1s do dispositivo, retira a pilha antiga e coloca a nova no lugar. Em poucos minutos, o teu dispositivo estar\u00e1 novamente operacional. Lembra-te de carregar completamente a bateria na primeira utiliza\u00e7\u00e3o para um desempenho \u00f3timo.   <\/p>\n<h3 data-start=\"2305\" data-end=\"2338\">Fiabilidade e seguran\u00e7a<\/h3>\n<p data-start=\"2340\" data-end=\"2728\">Como se trata de uma <strong data-start=\"2354\" data-end=\"2378\">bateria original Fysic<\/strong>, cumpre todas as normas de seguran\u00e7a relevantes. A prote\u00e7\u00e3o integrada contra a sobrecarga e o sobreaquecimento garante uma utiliza\u00e7\u00e3o sem preocupa\u00e7\u00f5es do teu aparelho. Ao contr\u00e1rio das baterias gen\u00e9ricas ou universais, esta bateria oferece a seguran\u00e7a de um produto concebido especificamente para o dispositivo a que se destina.  <\/p>\n<h3 data-start=\"2730\" data-end=\"2771\">Resumo das especifica\u00e7\u00f5es t\u00e9cnicas:<\/h3>\n<ul data-start=\"2773\" data-end=\"3017\">\n<li data-start=\"2773\" data-end=\"2814\">\n<p data-start=\"2775\" data-end=\"2814\"><strong data-start=\"2775\" data-end=\"2784\">Tipo:<\/strong> Bateria recarreg\u00e1vel de i\u00f5es de l\u00edtio<\/p>\n<\/li>\n<li data-start=\"2815\" data-end=\"2841\">\n<p data-start=\"2817\" data-end=\"2841\"><strong data-start=\"2817\" data-end=\"2830\">Tens\u00e3o:<\/strong> 3,7 volts<\/p>\n<\/li>\n<li data-start=\"2842\" data-end=\"2870\">\n<p data-start=\"2844\" data-end=\"2870\"><strong data-start=\"2844\" data-end=\"2859\">Capacidade:<\/strong> 1000 mAh<\/p>\n<\/li>\n<li data-start=\"2871\" data-end=\"2908\">\n<p data-start=\"2873\" data-end=\"2908\"><strong data-start=\"2873\" data-end=\"2892\">Compat\u00edvel com:<\/strong> Fysic FM-7810<\/p>\n<\/li>\n<li data-start=\"2909\" data-end=\"2966\">\n<p data-start=\"2911\" data-end=\"2966\"><strong data-start=\"2911\" data-end=\"2923\">Carrega:<\/strong> Atrav\u00e9s do carregador existente no dispositivo<\/p>\n<\/li>\n<li data-start=\"2967\" data-end=\"3017\">\n<p data-start=\"2969\" data-end=\"3017\"><strong data-start=\"2969\" data-end=\"2987\">Carater\u00edsticas:<\/strong> Original, seguro e duradouro<\/p>\n<\/li>\n<\/ul>\n<hr class=\"\" data-start=\"3019\" data-end=\"3022\">\n<p data-start=\"3024\" data-end=\"3057\"><strong data-start=\"3024\" data-end=\"3057\">Porqu\u00ea escolher esta bateria?<\/strong><\/p>\n<ul data-start=\"3059\" data-end=\"3336\">\n<li data-start=\"3059\" data-end=\"3110\">\n<p data-start=\"3061\" data-end=\"3110\">Bateria original - perfeita e fi\u00e1vel<\/p>\n<\/li>\n<li data-start=\"3111\" data-end=\"3152\">\n<p data-start=\"3113\" data-end=\"3152\">Prolonga a vida \u00fatil do teu dispositivo<\/p>\n<\/li>\n<li data-start=\"3153\" data-end=\"3201\">\n<p data-start=\"3155\" data-end=\"3201\">F\u00e1cil de instalar sem ferramentas<\/p>\n<\/li>\n<li data-start=\"3202\" data-end=\"3262\">\n<p data-start=\"3204\" data-end=\"3262\">Ideal para utiliza\u00e7\u00e3o di\u00e1ria e longo tempo de espera<\/p>\n<\/li>\n<li data-start=\"3263\" data-end=\"3336\">\n<p data-start=\"3265\" data-end=\"3336\">Adequado para quem valoriza a qualidade, a seguran\u00e7a e a prote\u00e7\u00e3o<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"3338\" data-end=\"3535\">Com a <strong data-start=\"3345\" data-end=\"3380\">bateria Fysic FM-7810 3.7V 1000mAh<\/strong>, escolhe a seguran\u00e7a, a facilidade de utiliza\u00e7\u00e3o e o desempenho a longo prazo. A solu\u00e7\u00e3o ideal quando o teu telem\u00f3vel j\u00e1 n\u00e3o dura tanto tempo ou deixa de carregar. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bateria original para Fysic FM-7810 - 3.7V \/ 1000mAh - Energia fi\u00e1vel para todos os dias Um telem\u00f3vel fi\u00e1vel merece uma bateria fi\u00e1vel. A bateria original Fysic FM-7810 foi especialmente concebida para substituir a bateria inclu\u00edda no telem\u00f3vel s\u00e9nior com o mesmo nome. Com uma capacidade de 1000mAh e uma voltagem de 3,7 volts, esta &hellip; <\/p>\n","protected":false},"featured_media":208751,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[14814],"product_tag":[],"class_list":["post-208749","product","type-product","status-publish","has-post-thumbnail","product_cat-baterias-pt-pt","grid-sizer","latest_post","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bateria Fysic FM-7810 (3.7V, 1000mAh) | Horend Goed Audiciens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bateria Fysic FM-7810 (3.7V, 1000mAh)\" \/>\n<meta property=\"og:description\" content=\"Bateria original para Fysic FM-7810 - 3.7V \/ 1000mAh - Energia fi\u00e1vel para todos os dias Um telem\u00f3vel fi\u00e1vel merece uma bateria fi\u00e1vel. A bateria original Fysic FM-7810 foi especialmente concebida para substituir a bateria inclu\u00edda no telem\u00f3vel s\u00e9nior com o mesmo nome. Com uma capacidade de 1000mAh e uma voltagem de 3,7 volts, esta &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T12:23:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/04\/fysic-fm-7810-accu-37v-1000mah.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/baterias-e-carregadores\\\/baterias-pt-pt\\\/bateria-fysic-fm-7810-3-7v-1000mah\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/baterias-e-carregadores\\\/baterias-pt-pt\\\/bateria-fysic-fm-7810-3-7v-1000mah\\\/\",\"name\":\"Bateria Fysic FM-7810 (3.7V, 1000mAh) | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/baterias-e-carregadores\\\/baterias-pt-pt\\\/bateria-fysic-fm-7810-3-7v-1000mah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/baterias-e-carregadores\\\/baterias-pt-pt\\\/bateria-fysic-fm-7810-3-7v-1000mah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fysic-fm-7810-accu-37v-1000mah.png\",\"datePublished\":\"2025-04-04T17:45:31+00:00\",\"dateModified\":\"2025-07-29T12:23:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/baterias-e-carregadores\\\/baterias-pt-pt\\\/bateria-fysic-fm-7810-3-7v-1000mah\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/baterias-e-carregadores\\\/baterias-pt-pt\\\/bateria-fysic-fm-7810-3-7v-1000mah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/baterias-e-carregadores\\\/baterias-pt-pt\\\/bateria-fysic-fm-7810-3-7v-1000mah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fysic-fm-7810-accu-37v-1000mah.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fysic-fm-7810-accu-37v-1000mah.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/baterias-e-carregadores\\\/baterias-pt-pt\\\/bateria-fysic-fm-7810-3-7v-1000mah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/compra\\\/produtos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bateria Fysic FM-7810 (3.7V, 1000mAh)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bateria Fysic FM-7810 (3.7V, 1000mAh) | Horend Goed Audiciens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/","og_locale":"pt_PT","og_type":"article","og_title":"Bateria Fysic FM-7810 (3.7V, 1000mAh)","og_description":"Bateria original para Fysic FM-7810 - 3.7V \/ 1000mAh - Energia fi\u00e1vel para todos os dias Um telem\u00f3vel fi\u00e1vel merece uma bateria fi\u00e1vel. A bateria original Fysic FM-7810 foi especialmente concebida para substituir a bateria inclu\u00edda no telem\u00f3vel s\u00e9nior com o mesmo nome. Com uma capacidade de 1000mAh e uma voltagem de 3,7 volts, esta &hellip;","og_url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","article_modified_time":"2025-07-29T12:23:44+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/04\/fysic-fm-7810-accu-37v-1000mah.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/","url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/","name":"Bateria Fysic FM-7810 (3.7V, 1000mAh) | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/04\/fysic-fm-7810-accu-37v-1000mah.png","datePublished":"2025-04-04T17:45:31+00:00","dateModified":"2025-07-29T12:23:44+00:00","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/04\/fysic-fm-7810-accu-37v-1000mah.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/04\/fysic-fm-7810-accu-37v-1000mah.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/baterias-e-carregadores\/baterias-pt-pt\/bateria-fysic-fm-7810-3-7v-1000mah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/www.horendgoed.nl\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.horendgoed.nl\/pt-pt\/compra\/produtos\/"},{"@type":"ListItem","position":3,"name":"Bateria Fysic FM-7810 (3.7V, 1000mAh)"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product\/208749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media\/208751"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media?parent=208749"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=208749"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=208749"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=208749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}