{"id":209125,"date":"2025-01-31T19:43:48","date_gmt":"2025-01-31T18:43:48","guid":{"rendered":"https:\/\/www.horendgoed.nl\/shop\/sem%20categoria\/resound-dome-rec-extra-pequeno\/"},"modified":"2025-09-15T16:07:37","modified_gmt":"2025-09-15T14:07:37","slug":"resound-dome-rec-extra-pequeno","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/","title":{"rendered":"Resound Dome Rec Extra Pequeno"},"content":{"rendered":"<p class=\"\" data-start=\"332\" data-end=\"644\">O <strong data-start=\"335\" data-end=\"367\">ReSound Dome Rec Extra Small<\/strong> \u00e9 um dome extremamente compacto e confort\u00e1vel, concebido especificamente para os <strong data-start=\"438\" data-end=\"487\">aparelhos auditivos ReSound com altifalante NP<\/strong>. Gra\u00e7as ao seu <strong data-start=\"501\" data-end=\"525\">tamanho extra pequeno<\/strong>, esta c\u00fapula \u00e9 ideal para pessoas com canais auditivos estreitos ou para aqueles que procuram um ajuste praticamente invis\u00edvel. <\/p>\n<p class=\"\" data-start=\"646\" data-end=\"877\">Apesar do seu tamanho subtil, esta c\u00fapula oferece uma excelente reprodu\u00e7\u00e3o de som e uma boa veda\u00e7\u00e3o, reduzindo o ru\u00eddo ambiente perturbador e o feedback. Perfeita para uso di\u00e1rio e f\u00e1cil de substituir. <\/p>\n<h3 class=\"\" data-start=\"884\" data-end=\"940\"><strong data-start=\"890\" data-end=\"940\">Carater\u00edsticas do ReSound Dome Rec Extra Small:<\/strong><\/h3>\n<ul data-start=\"942\" data-end=\"1338\">\n<li class=\"\" data-start=\"942\" data-end=\"1016\">\n<p class=\"\" data-start=\"944\" data-end=\"1016\"><strong data-start=\"944\" data-end=\"985\">Compat\u00edvel com aparelhos auditivos ReSound<\/strong> com <strong data-start=\"990\" data-end=\"1016\">altifalante\/altifalante NP<\/strong><\/p>\n<\/li>\n<li class=\"\" data-start=\"1017\" data-end=\"1083\">\n<p class=\"\" data-start=\"1019\" data-end=\"1083\"><strong data-start=\"1019\" data-end=\"1039\">Tamanho extra pequeno<\/strong> - para um ajuste discreto e confort\u00e1vel<\/p>\n<\/li>\n<li class=\"\" data-start=\"1084\" data-end=\"1138\">\n<p class=\"\" data-start=\"1086\" data-end=\"1138\">Ideal para utilizadores com <strong data-start=\"1117\" data-end=\"1138\">canais auditivos estreitos<\/strong><\/p>\n<\/li>\n<li class=\"\" data-start=\"1139\" data-end=\"1201\">\n<p class=\"\" data-start=\"1141\" data-end=\"1201\">Melhora <strong data-start=\"1154\" data-end=\"1174\">a qualidade do som<\/strong> e reduz <strong data-start=\"1189\" data-end=\"1201\">o feedback<\/strong><\/p>\n<\/li>\n<li class=\"\" data-start=\"1202\" data-end=\"1266\">\n<p class=\"\" data-start=\"1204\" data-end=\"1266\"><strong data-start=\"1204\" data-end=\"1232\">F\u00e1cil de substituir<\/strong> para uma utiliza\u00e7\u00e3o higi\u00e9nica di\u00e1ria<\/p>\n<\/li>\n<li class=\"\" data-start=\"1267\" data-end=\"1338\">\n<p class=\"\" data-start=\"1269\" data-end=\"1338\">Fornecido em embalagens pr\u00e1ticas (o n\u00famero depende do fabricante)<\/p>\n<\/li>\n<\/ul>\n<h3 class=\"\" data-start=\"1345\" data-end=\"1383\">Para quem \u00e9 que esta c\u00fapula \u00e9 adequada?<\/h3>\n<p class=\"\" data-start=\"1385\" data-end=\"1673\">A c\u00fapula Extra Small \u00e9 adequada para os utilizadores de <strong data-start=\"1437\" data-end=\"1478\">aparelhos auditivos ReSound com altifalante NP<\/strong> que necessitam de uma solu\u00e7\u00e3o compacta. \u00c9 perfeita para quem valoriza o conforto, a discri\u00e7\u00e3o e o desempenho. N\u00e3o \u00e9 adequada para outros tipos de altifalantes, como os M&amp;RIE ou os receptores normais.  <\/p>\n<h3 class=\"\" data-start=\"1680\" data-end=\"1705\">Conselhos de substitui\u00e7\u00e3o:<\/h3>\n<p class=\"\" data-start=\"1707\" data-end=\"1851\">Para um desempenho e higiene \u00f3ptimos, recomendamos a substitui\u00e7\u00e3o das c\u00fapulas a cada <strong data-start=\"1770\" data-end=\"1787\">4 a 6 semanas<\/strong>, ou mais cedo se houver sinais de desgaste ou sujidade.<\/p>\n<p class=\"\" data-start=\"1858\" data-end=\"1973\"><strong data-start=\"1858\" data-end=\"1903\">Encomenda j\u00e1 o ReSound Dome Rec Extra Small<\/strong> e experimenta a diferen\u00e7a de um ajuste discreto com o m\u00e1ximo conforto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ReSound Dome Rec Extra Small \u00e9 um dome extremamente compacto e confort\u00e1vel, concebido especificamente para os aparelhos auditivos ReSound com altifalante NP. Gra\u00e7as ao seu tamanho extra pequeno, esta c\u00fapula \u00e9 ideal para pessoas com canais auditivos estreitos ou para aqueles que procuram um ajuste praticamente invis\u00edvel. Apesar do seu tamanho subtil, esta c\u00fapula &hellip; <\/p>\n","protected":false},"featured_media":209128,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[14867],"product_tag":[14820],"class_list":["post-209125","product","type-product","status-publish","has-post-thumbnail","product_cat-cupulas-pt-pt","product_tag-ressoa","grid-sizer","latest_post","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resound Dome Rec Extra Pequeno | Horend Goed Audiciens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resound Dome Rec Extra Pequeno\" \/>\n<meta property=\"og:description\" content=\"O ReSound Dome Rec Extra Small \u00e9 um dome extremamente compacto e confort\u00e1vel, concebido especificamente para os aparelhos auditivos ReSound com altifalante NP. Gra\u00e7as ao seu tamanho extra pequeno, esta c\u00fapula \u00e9 ideal para pessoas com canais auditivos estreitos ou para aqueles que procuram um ajuste praticamente invis\u00edvel. Apesar do seu tamanho subtil, esta c\u00fapula &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T14:07:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/01\/resound-dome-rec-extra-small.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/resound-dome-rec-extra-pequeno\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/resound-dome-rec-extra-pequeno\\\/\",\"name\":\"Resound Dome Rec Extra Pequeno | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/resound-dome-rec-extra-pequeno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/resound-dome-rec-extra-pequeno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/resound-dome-rec-extra-small.png\",\"datePublished\":\"2025-01-31T18:43:48+00:00\",\"dateModified\":\"2025-09-15T14:07:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/resound-dome-rec-extra-pequeno\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/resound-dome-rec-extra-pequeno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/resound-dome-rec-extra-pequeno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/resound-dome-rec-extra-small.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/resound-dome-rec-extra-small.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/cupulas-pt-pt\\\/resound-dome-rec-extra-pequeno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/compra\\\/produtos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Resound Dome Rec Extra Pequeno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resound Dome Rec Extra Pequeno | Horend Goed Audiciens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/","og_locale":"pt_PT","og_type":"article","og_title":"Resound Dome Rec Extra Pequeno","og_description":"O ReSound Dome Rec Extra Small \u00e9 um dome extremamente compacto e confort\u00e1vel, concebido especificamente para os aparelhos auditivos ReSound com altifalante NP. Gra\u00e7as ao seu tamanho extra pequeno, esta c\u00fapula \u00e9 ideal para pessoas com canais auditivos estreitos ou para aqueles que procuram um ajuste praticamente invis\u00edvel. Apesar do seu tamanho subtil, esta c\u00fapula &hellip;","og_url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","article_modified_time":"2025-09-15T14:07:37+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/01\/resound-dome-rec-extra-small.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/","url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/","name":"Resound Dome Rec Extra Pequeno | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/01\/resound-dome-rec-extra-small.png","datePublished":"2025-01-31T18:43:48+00:00","dateModified":"2025-09-15T14:07:37+00:00","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/01\/resound-dome-rec-extra-small.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/01\/resound-dome-rec-extra-small.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/cupulas-pt-pt\/resound-dome-rec-extra-pequeno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/www.horendgoed.nl\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.horendgoed.nl\/pt-pt\/compra\/produtos\/"},{"@type":"ListItem","position":3,"name":"Resound Dome Rec Extra Pequeno"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product\/209125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media\/209128"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media?parent=209125"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=209125"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=209125"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=209125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}