{"id":209147,"date":"2025-01-31T19:17:39","date_gmt":"2025-01-31T18:17:39","guid":{"rendered":"https:\/\/www.horendgoed.nl\/shop\/sem%20categoria\/resound-bte-98-pitch-bend\/"},"modified":"2025-09-15T15:45:48","modified_gmt":"2025-09-15T13:45:48","slug":"resound-bte-98-pitch-bend","status":"publish","type":"product","link":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/","title":{"rendered":"Resound BTE 98 pitch bend"},"content":{"rendered":"<h1><strong>ReSound Tone Bend - Pe\u00e7a de substitui\u00e7\u00e3o para aparelhos auditivos para colocar atr\u00e1s da orelha (Tipo 98)<\/strong><\/h1>\n<p>Um aparelho auditivo \u00e9 composto por v\u00e1rias pe\u00e7as essenciais que contribuem para uma reprodu\u00e7\u00e3o \u00f3ptima do som e para o conforto de utiliza\u00e7\u00e3o. A <strong>curva de som ReSound<\/strong> \u00e9 uma pe\u00e7a substitu\u00edvel importante para os <strong>aparelhos auditivos retroauriculares<\/strong> <strong>da marca ReSound, tipo 98<\/strong>. Esta pe\u00e7a liga o altifalante do aparelho auditivo ao auricular e assegura a condu\u00e7\u00e3o correta do som.  <\/p>\n<p>Com o tempo, <strong>os arcos de tom<\/strong> podem desgastar-se, descolorir-se ou ficar obstru\u00eddos com sujidade e cera, o que pode afetar negativamente a qualidade do som. Substituir o gancho a tempo manter\u00e1 o teu aparelho auditivo a funcionar no seu melhor e ajudar-te-\u00e1 a desfrutar de um som claro e natural. <\/p>\n<h2><strong>Porqu\u00ea substituir um ReSound Tone Bend?<\/strong><\/h2>\n<p><strong>Manuten\u00e7\u00e3o da qualidade do som<\/strong> - Evita a distor\u00e7\u00e3o ou atenua\u00e7\u00e3o do som.<br \/>\n<strong>Aumenta o conforto<\/strong> - Uma nova curva de tom ajusta-se melhor e \u00e9 mais confort\u00e1vel.<br \/>\n<strong>Evita o entupimento e o desgaste<\/strong> - A substitui\u00e7\u00e3o assegura a higiene e o bom funcionamento dos aparelhos auditivos.<br \/>\n<strong>Instala\u00e7\u00e3o f\u00e1cil<\/strong> - O tone bend \u00e9 f\u00e1cil de substituir sem conhecimentos especializados.<br \/>\n<strong>Especialmente para ReSound tipo 98<\/strong> - Adequado para este modelo particular de aparelhos auditivos retroauriculares.<\/p>\n<hr>\n<h2><strong>O que \u00e9 um tone bend?<\/strong><\/h2>\n<p>A <strong>curva de tom<\/strong> \u00e9 o tubo de pl\u00e1stico curvo que liga <strong>o tubo de som do aparelho auditivo<\/strong> ao <strong>auricular<\/strong>. Esta pe\u00e7a desempenha um papel crucial no funcionamento do teu aparelho auditivo. Uma curva de tom danificada ou obstru\u00edda pode <strong>afetar a transmiss\u00e3o do som<\/strong>, tornando o teu aparelho auditivo menos funcional.  <\/p>\n<p>A adapta\u00e7\u00e3o regular de um novo tone bend evita que o teu aparelho auditivo pare\u00e7a aborrecido ou distorcido. Isto n\u00e3o s\u00f3 contribui para <strong>uma melhor audi\u00e7\u00e3o<\/strong>, como tamb\u00e9m aumenta <strong>o conforto de utiliza\u00e7\u00e3o<\/strong> e prolonga a vida \u00fatil do teu aparelho auditivo. <\/p>\n<hr>\n<h2><strong>Quando deves substituir o teu Tone Bend?<\/strong><\/h2>\n<ul>\n<li><strong>Volume de som reduzido<\/strong> - Se notares que o som do teu aparelho auditivo se torna mais fraco, a causa pode ser uma curva de tom entupida.<\/li>\n<li><strong>Som distorcido<\/strong> - Um tone bend danificado pode criar um som n\u00e3o natural ou oco.<\/li>\n<li><strong>Descolora\u00e7\u00e3o ou desgaste<\/strong> - Com o tempo, o material do tone bend pode descolorir ou endurecer, afectando o seu ajuste e fun\u00e7\u00e3o.<\/li>\n<li><strong>Higiene<\/strong> - A substitui\u00e7\u00e3o regular evita a acumula\u00e7\u00e3o de sujidade e bact\u00e9rias no aparelho auditivo.<\/li>\n<\/ul>\n<p>Recomenda-se a substitui\u00e7\u00e3o de um tone bend a cada <strong>3 a 6 meses<\/strong>, dependendo do uso e da manuten\u00e7\u00e3o.<\/p>\n<hr>\n<h2><strong>Como substituir o gancho de orelha ReSound?<\/strong><\/h2>\n<p>Substituir um tone bend \u00e9 f\u00e1cil e pode ser feito em minutos:<\/p>\n<ol>\n<li><strong>Retira a curva de tonalidade antiga<\/strong> do teu aparelho auditivo, puxando-a com cuidado.<\/li>\n<li><strong>Limpa o auricular<\/strong> antes de colocar o novo gancho.<\/li>\n<li><strong>Coloca a nova curva de tonalidade<\/strong> firmemente no aparelho auditivo e certifica-te de que est\u00e1 segura.<\/li>\n<li><strong>Verifica se o aparelho auditivo est\u00e1 a funcionar corretamente<\/strong> e, se necess\u00e1rio, ajusta a posi\u00e7\u00e3o para um conforto de utiliza\u00e7\u00e3o ideal.<\/li>\n<\/ol>\n<p>Se n\u00e3o tiveres a certeza sobre a substitui\u00e7\u00e3o do tone bend, podes sempre pedir conselhos ao teu profissional de sa\u00fade auditiva.<\/p>\n<hr>\n<h2><strong>Porqu\u00ea escolher o gancho de ouvido ReSound Type 98?<\/strong><\/h2>\n<ul>\n<li><strong>Produto original ReSound<\/strong> - Adapta\u00e7\u00e3o e compatibilidade perfeitas com o teu aparelho auditivo.<\/li>\n<li><strong>Especialmente concebido para aparelhos auditivos por detr\u00e1s da orelha<\/strong> - Apenas adequado para modelos <strong>ReSound tipo 98<\/strong>.<\/li>\n<li><strong>Materiais de alta qualidade<\/strong> - Dur\u00e1veis, flex\u00edveis e confort\u00e1veis para a utiliza\u00e7\u00e3o di\u00e1ria.<\/li>\n<li><strong>Instala\u00e7\u00e3o f\u00e1cil<\/strong> - Substitui-se a si pr\u00f3prio sem conhecimentos t\u00e9cnicos.<\/li>\n<\/ul>\n<hr>\n<h2><strong>Conclus\u00e3o: Assegura um som \u00f3timo com uma nova curva de tonalidade<\/strong><\/h2>\n<p>Um aparelho auditivo que funciona corretamente come\u00e7a com as pe\u00e7as certas. O <strong>ReSound Tone Bend para o Tipo 98<\/strong> oferece uma substitui\u00e7\u00e3o fi\u00e1vel que <strong>melhora a qualidade do som, aumenta o conforto e prolonga a vida \u00fatil do teu aparelho auditivo<\/strong>. <\/p>\n<p>N\u00e3o esperes que o teu tone bend se desgaste ou fique entupido - substitui-o a tempo e desfruta novamente de <strong>um som claro e natural<\/strong>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ReSound Tone Bend - Pe\u00e7a de substitui\u00e7\u00e3o para aparelhos auditivos para colocar atr\u00e1s da orelha (Tipo 98) Um aparelho auditivo \u00e9 composto por v\u00e1rias pe\u00e7as essenciais que contribuem para uma reprodu\u00e7\u00e3o \u00f3ptima do som e para o conforto de utiliza\u00e7\u00e3o. A curva de som ReSound \u00e9 uma pe\u00e7a substitu\u00edvel importante para os aparelhos auditivos retroauriculares &hellip; <\/p>\n","protected":false},"featured_media":209138,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[15118],"product_tag":[14820],"class_list":["post-209147","product","type-product","status-publish","has-post-thumbnail","product_cat-curvas-de-tom","product_tag-ressoa","grid-sizer","latest_post","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Resound BTE 98 pitch bend | Horend Goed Audiciens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resound BTE 98 pitch bend\" \/>\n<meta property=\"og:description\" content=\"ReSound Tone Bend - Pe\u00e7a de substitui\u00e7\u00e3o para aparelhos auditivos para colocar atr\u00e1s da orelha (Tipo 98) Um aparelho auditivo \u00e9 composto por v\u00e1rias pe\u00e7as essenciais que contribuem para uma reprodu\u00e7\u00e3o \u00f3ptima do som e para o conforto de utiliza\u00e7\u00e3o. A curva de som ReSound \u00e9 uma pe\u00e7a substitu\u00edvel importante para os aparelhos auditivos retroauriculares &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/\" \/>\n<meta property=\"og:site_name\" content=\"Horend Goed Audiciens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/horendgoed\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T13:45:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/01\/resound-aho-77-67-toonbocht-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/curvas-de-tom\\\/resound-bte-98-pitch-bend\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/curvas-de-tom\\\/resound-bte-98-pitch-bend\\\/\",\"name\":\"Resound BTE 98 pitch bend | Horend Goed Audiciens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/curvas-de-tom\\\/resound-bte-98-pitch-bend\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/curvas-de-tom\\\/resound-bte-98-pitch-bend\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/resound-aho-77-67-toonbocht-2.png\",\"datePublished\":\"2025-01-31T18:17:39+00:00\",\"dateModified\":\"2025-09-15T13:45:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/curvas-de-tom\\\/resound-bte-98-pitch-bend\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/curvas-de-tom\\\/resound-bte-98-pitch-bend\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/curvas-de-tom\\\/resound-bte-98-pitch-bend\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/resound-aho-77-67-toonbocht-2.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/resound-aho-77-67-toonbocht-2.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/shop\\\/acessorios\\\/curvas-de-tom\\\/resound-bte-98-pitch-bend\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/compra\\\/produtos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Resound BTE 98 pitch bend\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"name\":\"Horend Goed Audiciens\",\"description\":\"Luistert Beter\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#organization\",\"name\":\"Horend Goed\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"contentUrl\":\"https:\\\/\\\/www.horendgoed.nl\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Logo-groot-e1621862526979.png\",\"width\":509,\"height\":100,\"caption\":\"Horend Goed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.horendgoed.nl\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/horendgoed\",\"https:\\\/\\\/www.instagram.com\\\/horendgoed\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/horend-goed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@horendgoed\"],\"email\":\"info@horendgoed.nl\",\"telephone\":\"075 20 25 203\",\"vatID\":\"NL 853 756 193 B01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Resound BTE 98 pitch bend | Horend Goed Audiciens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/","og_locale":"pt_PT","og_type":"article","og_title":"Resound BTE 98 pitch bend","og_description":"ReSound Tone Bend - Pe\u00e7a de substitui\u00e7\u00e3o para aparelhos auditivos para colocar atr\u00e1s da orelha (Tipo 98) Um aparelho auditivo \u00e9 composto por v\u00e1rias pe\u00e7as essenciais que contribuem para uma reprodu\u00e7\u00e3o \u00f3ptima do som e para o conforto de utiliza\u00e7\u00e3o. A curva de som ReSound \u00e9 uma pe\u00e7a substitu\u00edvel importante para os aparelhos auditivos retroauriculares &hellip;","og_url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/","og_site_name":"Horend Goed Audiciens","article_publisher":"https:\/\/www.facebook.com\/horendgoed","article_modified_time":"2025-09-15T13:45:48+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/01\/resound-aho-77-67-toonbocht-2.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/","url":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/","name":"Resound BTE 98 pitch bend | Horend Goed Audiciens","isPartOf":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/#primaryimage"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/#primaryimage"},"thumbnailUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/01\/resound-aho-77-67-toonbocht-2.png","datePublished":"2025-01-31T18:17:39+00:00","dateModified":"2025-09-15T13:45:48+00:00","breadcrumb":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/#primaryimage","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/01\/resound-aho-77-67-toonbocht-2.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2025\/01\/resound-aho-77-67-toonbocht-2.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/shop\/acessorios\/curvas-de-tom\/resound-bte-98-pitch-bend\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/www.horendgoed.nl\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.horendgoed.nl\/pt-pt\/compra\/produtos\/"},{"@type":"ListItem","position":3,"name":"Resound BTE 98 pitch bend"}]},{"@type":"WebSite","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#website","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","name":"Horend Goed Audiciens","description":"Luistert Beter","publisher":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.horendgoed.nl\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#organization","name":"Horend Goed","url":"https:\/\/www.horendgoed.nl\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","contentUrl":"https:\/\/www.horendgoed.nl\/wp-content\/uploads\/2021\/05\/Logo-groot-e1621862526979.png","width":509,"height":100,"caption":"Horend Goed"},"image":{"@id":"https:\/\/www.horendgoed.nl\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/horendgoed","https:\/\/www.instagram.com\/horendgoed\/","https:\/\/www.linkedin.com\/company\/horend-goed\/","https:\/\/www.youtube.com\/@horendgoed"],"email":"info@horendgoed.nl","telephone":"075 20 25 203","vatID":"NL 853 756 193 B01"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product\/209147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media\/209138"}],"wp:attachment":[{"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/media?parent=209147"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=209147"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=209147"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.horendgoed.nl\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=209147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}